{"id":136051,"date":"2017-06-12T13:17:59","date_gmt":"2017-06-12T13:17:59","guid":{"rendered":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Venezia-8.jpg"},"modified":"2017-06-12T13:17:59","modified_gmt":"2017-06-12T13:17:59","slug":"venezia-8-2","status":"inherit","type":"attachment","link":"https:\/\/mirandalovestravelling.com\/es\/italia-venecia\/venezia-8-2\/","title":{"rendered":"Venezia- (8)"},"author":11,"comment_status":"open","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"yoast_head":"<title>Venezia- (8) - Miranda Loves Travelling<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Venezia- (8) - Miranda Loves Travelling\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mirandalovestravelling.com\/es\/italia-venecia\/venezia-8-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Miranda Loves Travelling\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Venezia-8.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/italia-venecia\/venezia-8-2\/\",\"url\":\"https:\/\/mirandalovestravelling.com\/es\/italia-venecia\/venezia-8-2\/\",\"name\":\"Venezia- (8) - Miranda Loves Travelling\",\"isPartOf\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/#website\"},\"datePublished\":\"2017-06-12T13:17:59+00:00\",\"dateModified\":\"2017-06-12T13:17:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/italia-venecia\/venezia-8-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mirandalovestravelling.com\/es\/italia-venecia\/venezia-8-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/italia-venecia\/venezia-8-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mirandalovestravelling.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Italia\",\"item\":\"https:\/\/mirandalovestravelling.com\/es\/location\/italia-es\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Venecia\",\"item\":\"https:\/\/mirandalovestravelling.com\/es\/location\/italia-es\/venecia\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Italia Venecia\",\"item\":\"https:\/\/mirandalovestravelling.com\/es\/italia-venecia\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Venezia- (8)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/#website\",\"url\":\"https:\/\/mirandalovestravelling.com\/es\/\",\"name\":\"Miranda Loves Travelling\",\"description\":\"Mi diario de viaje\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mirandalovestravelling.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>","yoast_head_json":{"title":"Venezia- (8) - Miranda Loves Travelling","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Venezia- (8) - Miranda Loves Travelling","og_url":"https:\/\/mirandalovestravelling.com\/es\/italia-venecia\/venezia-8-2\/","og_site_name":"Miranda Loves Travelling","og_image":[{"width":1920,"height":1272,"url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Venezia-8.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mirandalovestravelling.com\/es\/italia-venecia\/venezia-8-2\/","url":"https:\/\/mirandalovestravelling.com\/es\/italia-venecia\/venezia-8-2\/","name":"Venezia- (8) - Miranda Loves Travelling","isPartOf":{"@id":"https:\/\/mirandalovestravelling.com\/es\/#website"},"datePublished":"2017-06-12T13:17:59+00:00","dateModified":"2017-06-12T13:17:59+00:00","breadcrumb":{"@id":"https:\/\/mirandalovestravelling.com\/es\/italia-venecia\/venezia-8-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mirandalovestravelling.com\/es\/italia-venecia\/venezia-8-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mirandalovestravelling.com\/es\/italia-venecia\/venezia-8-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mirandalovestravelling.com\/es\/"},{"@type":"ListItem","position":2,"name":"Italia","item":"https:\/\/mirandalovestravelling.com\/es\/location\/italia-es\/"},{"@type":"ListItem","position":3,"name":"Venecia","item":"https:\/\/mirandalovestravelling.com\/es\/location\/italia-es\/venecia\/"},{"@type":"ListItem","position":4,"name":"Italia Venecia","item":"https:\/\/mirandalovestravelling.com\/es\/italia-venecia\/"},{"@type":"ListItem","position":5,"name":"Venezia- (8)"}]},{"@type":"WebSite","@id":"https:\/\/mirandalovestravelling.com\/es\/#website","url":"https:\/\/mirandalovestravelling.com\/es\/","name":"Miranda Loves Travelling","description":"Mi diario de viaje","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mirandalovestravelling.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Venezia-8.jpg'><img width=\"1920\" height=\"1272\" src=\"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Venezia-8.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Venezia-8.jpg 1920w, https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Venezia-8-768x509.jpg 768w, https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Venezia-8-336x223.jpg 336w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":1272,"file":"2016\/08\/Venezia-8.jpg","sizes":{"thumbnail":{"file":"Venezia-8-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Venezia-8-150x150.jpg"},"medium_large":{"file":"Venezia-8-768x509.jpg","width":768,"height":509,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Venezia-8-768x509.jpg"},"mlt-medium":{"file":"Venezia-8-336x223.jpg","width":336,"height":223,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Venezia-8-336x223.jpg"},"mlt-small":{"file":"Venezia-8-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Venezia-8-80x60.jpg"},"full":{"file":"Venezia-8.jpg","width":1920,"height":1272,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Venezia-8.jpg"}},"image_meta":{"aperture":"5.6","credit":"Picasa","camera":"NIKON D5100","caption":"","created_timestamp":"1491039644","copyright":"","focal_length":"200","iso":"100","shutter_speed":"0.00125","title":"","orientation":"0","keywords":["Venezia"]},"ShortPixel":{"type":"lossy","exifKept":"0","date":"2019-05-06 10:07:55","thumbsOpt":4,"thumbsOptList":["Venezia-8-150x150.jpg","Venezia-8-768x509.jpg","Venezia-8-336x223.jpg","Venezia-8-80x60.jpg"],"excludeSizes":[],"retinasOpt":0},"ShortPixelImprovement":"81.68"},"post":136614,"source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Venezia-8.jpg","_links":{"self":[{"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/media\/136051"}],"collection":[{"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/users\/11"}]}}