{"id":143902,"date":"2016-08-11T16:08:25","date_gmt":"2016-08-11T16:08:25","guid":{"rendered":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Nida-16.jpg"},"modified":"2016-08-11T16:08:25","modified_gmt":"2016-08-11T16:08:25","slug":"nida-16-2","status":"inherit","type":"attachment","link":"https:\/\/mirandalovestravelling.com\/es\/lithuania-nida\/nida-16-2\/","title":{"rendered":"Lithuania, Nida &#8211; blue house and wooden boat, Sept.2014"},"author":11,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"yoast_head":"<title>Lithuania, Nida - blue house and wooden boat, Sept.2014 - Miranda Loves Travelling<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lithuania, Nida - blue house and wooden boat, Sept.2014 - Miranda Loves Travelling\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mirandalovestravelling.com\/es\/lithuania-nida\/nida-16-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Miranda Loves Travelling\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Nida-16.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"662\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/lithuania-nida\/nida-16-2\/\",\"url\":\"https:\/\/mirandalovestravelling.com\/es\/lithuania-nida\/nida-16-2\/\",\"name\":\"Lithuania, Nida - blue house and wooden boat, Sept.2014 - Miranda Loves Travelling\",\"isPartOf\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/#website\"},\"datePublished\":\"2016-08-11T16:08:25+00:00\",\"dateModified\":\"2016-08-11T16:08:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/lithuania-nida\/nida-16-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mirandalovestravelling.com\/es\/lithuania-nida\/nida-16-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/lithuania-nida\/nida-16-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mirandalovestravelling.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lituania\",\"item\":\"https:\/\/mirandalovestravelling.com\/es\/location\/lituania-es\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nida\",\"item\":\"https:\/\/mirandalovestravelling.com\/es\/location\/lituania-es\/nida-es\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Lithuania Nida\",\"item\":\"https:\/\/mirandalovestravelling.com\/es\/lithuania-nida\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Lithuania, Nida &#8211; blue house and wooden boat, Sept.2014\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/#website\",\"url\":\"https:\/\/mirandalovestravelling.com\/es\/\",\"name\":\"Miranda Loves Travelling\",\"description\":\"Mi diario de viaje\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mirandalovestravelling.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>","yoast_head_json":{"title":"Lithuania, Nida - blue house and wooden boat, Sept.2014 - Miranda Loves Travelling","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Lithuania, Nida - blue house and wooden boat, Sept.2014 - Miranda Loves Travelling","og_url":"https:\/\/mirandalovestravelling.com\/es\/lithuania-nida\/nida-16-2\/","og_site_name":"Miranda Loves Travelling","og_image":[{"width":662,"height":1000,"url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Nida-16.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mirandalovestravelling.com\/es\/lithuania-nida\/nida-16-2\/","url":"https:\/\/mirandalovestravelling.com\/es\/lithuania-nida\/nida-16-2\/","name":"Lithuania, Nida - blue house and wooden boat, Sept.2014 - Miranda Loves Travelling","isPartOf":{"@id":"https:\/\/mirandalovestravelling.com\/es\/#website"},"datePublished":"2016-08-11T16:08:25+00:00","dateModified":"2016-08-11T16:08:25+00:00","breadcrumb":{"@id":"https:\/\/mirandalovestravelling.com\/es\/lithuania-nida\/nida-16-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mirandalovestravelling.com\/es\/lithuania-nida\/nida-16-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mirandalovestravelling.com\/es\/lithuania-nida\/nida-16-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mirandalovestravelling.com\/es\/"},{"@type":"ListItem","position":2,"name":"Lituania","item":"https:\/\/mirandalovestravelling.com\/es\/location\/lituania-es\/"},{"@type":"ListItem","position":3,"name":"Nida","item":"https:\/\/mirandalovestravelling.com\/es\/location\/lituania-es\/nida-es\/"},{"@type":"ListItem","position":4,"name":"Lithuania Nida","item":"https:\/\/mirandalovestravelling.com\/es\/lithuania-nida\/"},{"@type":"ListItem","position":5,"name":"Lithuania, Nida &#8211; blue house and wooden boat, Sept.2014"}]},{"@type":"WebSite","@id":"https:\/\/mirandalovestravelling.com\/es\/#website","url":"https:\/\/mirandalovestravelling.com\/es\/","name":"Miranda Loves Travelling","description":"Mi diario de viaje","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mirandalovestravelling.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Nida-16.jpg'><img width=\"662\" height=\"1000\" src=\"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Nida-16.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":662,"height":1000,"file":"2016\/08\/Nida-16.jpg","sizes":{"thumbnail":{"file":"Nida-16-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Nida-16-150x150.jpg"},"mlt-medium":{"file":"Nida-16-326x245.jpg","width":326,"height":245,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Nida-16-326x245.jpg"},"mlt-small":{"file":"Nida-16-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Nida-16-80x60.jpg"},"full":{"file":"Nida-16.jpg","width":662,"height":1000,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Nida-16.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ShortPixel":{"type":"lossy","exifKept":"0","date":"2019-05-04 20:45:21","thumbsOpt":3,"thumbsOptList":["Nida-16-150x150.jpg","Nida-16-326x245.jpg","Nida-16-80x60.jpg"],"excludeSizes":[],"retinasOpt":0},"ShortPixelImprovement":"83.92"},"post":143939,"source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Nida-16.jpg","_links":{"self":[{"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/media\/143902"}],"collection":[{"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/users\/11"}]}}