{"id":148378,"date":"2016-08-11T07:46:00","date_gmt":"2016-08-11T07:46:00","guid":{"rendered":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Amalfi-Coast-32.jpg"},"modified":"2016-08-11T07:46:00","modified_gmt":"2016-08-11T07:46:00","slug":"amalfi-coast-32-2-2","status":"inherit","type":"attachment","link":"https:\/\/mirandalovestravelling.com\/es\/italy-amalfi-coast\/amalfi-coast-32-2-2\/","title":{"rendered":"Ravello &#8211; local men, Oct.2015"},"author":11,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"yoast_head":"<title>Ravello - local men, Oct.2015 - Miranda Loves Travelling<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ravello - local men, Oct.2015 - Miranda Loves Travelling\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mirandalovestravelling.com\/es\/italy-amalfi-coast\/amalfi-coast-32-2-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Miranda Loves Travelling\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Amalfi-Coast-32.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"721\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/italy-amalfi-coast\/amalfi-coast-32-2-2\/\",\"url\":\"https:\/\/mirandalovestravelling.com\/es\/italy-amalfi-coast\/amalfi-coast-32-2-2\/\",\"name\":\"Ravello - local men, Oct.2015 - Miranda Loves Travelling\",\"isPartOf\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/#website\"},\"datePublished\":\"2016-08-11T07:46:00+00:00\",\"dateModified\":\"2016-08-11T07:46:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/italy-amalfi-coast\/amalfi-coast-32-2-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mirandalovestravelling.com\/es\/italy-amalfi-coast\/amalfi-coast-32-2-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/italy-amalfi-coast\/amalfi-coast-32-2-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mirandalovestravelling.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Italia\",\"item\":\"https:\/\/mirandalovestravelling.com\/es\/location\/italia-es\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Costa Amalfitana\",\"item\":\"https:\/\/mirandalovestravelling.com\/es\/location\/italia-es\/costa-amalfitana\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Italy Amalfi Coast\",\"item\":\"https:\/\/mirandalovestravelling.com\/es\/italy-amalfi-coast\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Ravello &#8211; local men, Oct.2015\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/#website\",\"url\":\"https:\/\/mirandalovestravelling.com\/es\/\",\"name\":\"Miranda Loves Travelling\",\"description\":\"Mi diario de viaje\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mirandalovestravelling.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>","yoast_head_json":{"title":"Ravello - local men, Oct.2015 - Miranda Loves Travelling","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Ravello - local men, Oct.2015 - Miranda Loves Travelling","og_url":"https:\/\/mirandalovestravelling.com\/es\/italy-amalfi-coast\/amalfi-coast-32-2-2\/","og_site_name":"Miranda Loves Travelling","og_image":[{"width":1000,"height":721,"url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Amalfi-Coast-32.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mirandalovestravelling.com\/es\/italy-amalfi-coast\/amalfi-coast-32-2-2\/","url":"https:\/\/mirandalovestravelling.com\/es\/italy-amalfi-coast\/amalfi-coast-32-2-2\/","name":"Ravello - local men, Oct.2015 - Miranda Loves Travelling","isPartOf":{"@id":"https:\/\/mirandalovestravelling.com\/es\/#website"},"datePublished":"2016-08-11T07:46:00+00:00","dateModified":"2016-08-11T07:46:00+00:00","breadcrumb":{"@id":"https:\/\/mirandalovestravelling.com\/es\/italy-amalfi-coast\/amalfi-coast-32-2-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mirandalovestravelling.com\/es\/italy-amalfi-coast\/amalfi-coast-32-2-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mirandalovestravelling.com\/es\/italy-amalfi-coast\/amalfi-coast-32-2-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mirandalovestravelling.com\/es\/"},{"@type":"ListItem","position":2,"name":"Italia","item":"https:\/\/mirandalovestravelling.com\/es\/location\/italia-es\/"},{"@type":"ListItem","position":3,"name":"Costa Amalfitana","item":"https:\/\/mirandalovestravelling.com\/es\/location\/italia-es\/costa-amalfitana\/"},{"@type":"ListItem","position":4,"name":"Italy Amalfi Coast","item":"https:\/\/mirandalovestravelling.com\/es\/italy-amalfi-coast\/"},{"@type":"ListItem","position":5,"name":"Ravello &#8211; local men, Oct.2015"}]},{"@type":"WebSite","@id":"https:\/\/mirandalovestravelling.com\/es\/#website","url":"https:\/\/mirandalovestravelling.com\/es\/","name":"Miranda Loves Travelling","description":"Mi diario de viaje","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mirandalovestravelling.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Amalfi-Coast-32.jpg'><img width=\"1000\" height=\"721\" src=\"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Amalfi-Coast-32.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Amalfi-Coast-32.jpg 1000w, https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Amalfi-Coast-32-768x554.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1000,"height":721,"file":"2016\/08\/Amalfi-Coast-32.jpg","sizes":{"thumbnail":{"file":"Amalfi-Coast-32-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Amalfi-Coast-32-150x150.jpg"},"medium_large":{"file":"Amalfi-Coast-32-768x554.jpg","width":768,"height":554,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Amalfi-Coast-32-768x554.jpg"},"mlt-medium":{"file":"Amalfi-Coast-32-326x245.jpg","width":326,"height":245,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Amalfi-Coast-32-326x245.jpg"},"mlt-small":{"file":"Amalfi-Coast-32-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Amalfi-Coast-32-80x60.jpg"},"full":{"file":"Amalfi-Coast-32.jpg","width":1000,"height":721,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Amalfi-Coast-32.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ShortPixel":{"type":"lossy","exifKept":"0","date":"2019-05-03 04:27:17","thumbsOpt":4,"thumbsOptList":["Amalfi-Coast-32-150x150.jpg","Amalfi-Coast-32-768x554.jpg","Amalfi-Coast-32-326x245.jpg","Amalfi-Coast-32-80x60.jpg"],"excludeSizes":[],"retinasOpt":0},"ShortPixelImprovement":"76.07"},"post":148481,"source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Amalfi-Coast-32.jpg","_links":{"self":[{"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/media\/148378"}],"collection":[{"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/users\/11"}]}}