{"id":153630,"date":"2016-08-09T09:40:18","date_gmt":"2016-08-09T09:40:18","guid":{"rendered":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/cuba-havana-malecon-boy.jpg"},"modified":"2016-08-09T09:40:18","modified_gmt":"2016-08-09T09:40:18","slug":"cuba-havana-malecon-boy-3","status":"inherit","type":"attachment","link":"https:\/\/mirandalovestravelling.com\/es\/cuba-havana\/cuba-havana-malecon-boy-3\/","title":{"rendered":"Cuba, Havana &#8211; Malecon boy, 2010"},"author":11,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"yoast_head":"<title>Cuba, Havana - Malecon boy, 2010 - Miranda Loves Travelling<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuba, Havana - Malecon boy, 2010 - Miranda Loves Travelling\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mirandalovestravelling.com\/es\/cuba-havana\/cuba-havana-malecon-boy-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Miranda Loves Travelling\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/cuba-havana-malecon-boy.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/cuba-havana\/cuba-havana-malecon-boy-3\/\",\"url\":\"https:\/\/mirandalovestravelling.com\/es\/cuba-havana\/cuba-havana-malecon-boy-3\/\",\"name\":\"Cuba, Havana - Malecon boy, 2010 - Miranda Loves Travelling\",\"isPartOf\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/#website\"},\"datePublished\":\"2016-08-09T09:40:18+00:00\",\"dateModified\":\"2016-08-09T09:40:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/cuba-havana\/cuba-havana-malecon-boy-3\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mirandalovestravelling.com\/es\/cuba-havana\/cuba-havana-malecon-boy-3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/cuba-havana\/cuba-havana-malecon-boy-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mirandalovestravelling.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuba Havana\",\"item\":\"https:\/\/mirandalovestravelling.com\/es\/cuba-havana\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cuba, Havana &#8211; Malecon boy, 2010\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/#website\",\"url\":\"https:\/\/mirandalovestravelling.com\/es\/\",\"name\":\"Miranda Loves Travelling\",\"description\":\"Mi diario de viaje\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mirandalovestravelling.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>","yoast_head_json":{"title":"Cuba, Havana - Malecon boy, 2010 - Miranda Loves Travelling","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Cuba, Havana - Malecon boy, 2010 - Miranda Loves Travelling","og_url":"https:\/\/mirandalovestravelling.com\/es\/cuba-havana\/cuba-havana-malecon-boy-3\/","og_site_name":"Miranda Loves Travelling","og_image":[{"width":800,"height":534,"url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/cuba-havana-malecon-boy.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mirandalovestravelling.com\/es\/cuba-havana\/cuba-havana-malecon-boy-3\/","url":"https:\/\/mirandalovestravelling.com\/es\/cuba-havana\/cuba-havana-malecon-boy-3\/","name":"Cuba, Havana - Malecon boy, 2010 - Miranda Loves Travelling","isPartOf":{"@id":"https:\/\/mirandalovestravelling.com\/es\/#website"},"datePublished":"2016-08-09T09:40:18+00:00","dateModified":"2016-08-09T09:40:18+00:00","breadcrumb":{"@id":"https:\/\/mirandalovestravelling.com\/es\/cuba-havana\/cuba-havana-malecon-boy-3\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mirandalovestravelling.com\/es\/cuba-havana\/cuba-havana-malecon-boy-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mirandalovestravelling.com\/es\/cuba-havana\/cuba-havana-malecon-boy-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mirandalovestravelling.com\/es\/"},{"@type":"ListItem","position":2,"name":"Cuba Havana","item":"https:\/\/mirandalovestravelling.com\/es\/cuba-havana\/"},{"@type":"ListItem","position":3,"name":"Cuba, Havana &#8211; Malecon boy, 2010"}]},{"@type":"WebSite","@id":"https:\/\/mirandalovestravelling.com\/es\/#website","url":"https:\/\/mirandalovestravelling.com\/es\/","name":"Miranda Loves Travelling","description":"Mi diario de viaje","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mirandalovestravelling.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/mirandalovestravelling.com\/media\/2016\/08\/cuba-havana-malecon-boy.jpg'><img width=\"800\" height=\"534\" src=\"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/cuba-havana-malecon-boy.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/cuba-havana-malecon-boy.jpg 800w, https:\/\/mirandalovestravelling.com\/media\/2016\/08\/cuba-havana-malecon-boy-768x513.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":534,"file":"2016\/08\/cuba-havana-malecon-boy.jpg","sizes":{"thumbnail":{"file":"cuba-havana-malecon-boy-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/cuba-havana-malecon-boy-150x150.jpg"},"medium_large":{"file":"cuba-havana-malecon-boy-768x513.jpg","width":768,"height":513,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/cuba-havana-malecon-boy-768x513.jpg"},"mlt-medium":{"file":"cuba-havana-malecon-boy-326x245.jpg","width":326,"height":245,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/cuba-havana-malecon-boy-326x245.jpg"},"mlt-small":{"file":"cuba-havana-malecon-boy-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/cuba-havana-malecon-boy-80x60.jpg"},"full":{"file":"cuba-havana-malecon-boy.jpg","width":800,"height":534,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/cuba-havana-malecon-boy.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ShortPixel":{"type":"lossy","exifKept":"0","date":"2019-04-29 11:34:20","thumbsOpt":4,"thumbsOptList":["cuba-havana-malecon-boy-150x150.jpg","cuba-havana-malecon-boy-768x513.jpg","cuba-havana-malecon-boy-326x245.jpg","cuba-havana-malecon-boy-80x60.jpg"],"excludeSizes":[],"retinasOpt":0},"ShortPixelImprovement":"33.18"},"post":153735,"source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/cuba-havana-malecon-boy.jpg","_links":{"self":[{"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/media\/153630"}],"collection":[{"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/users\/11"}]}}