{"id":174432,"date":"2018-02-06T10:13:38","date_gmt":"2018-02-06T10:13:38","guid":{"rendered":"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Guardiagrele-5.jpg"},"modified":"2018-02-06T10:13:38","modified_gmt":"2018-02-06T10:13:38","slug":"guardiagrele-5-2","status":"inherit","type":"attachment","link":"https:\/\/mirandalovestravelling.com\/es\/italia-abruzos\/guardiagrele-5-2\/","title":{"rendered":"Guardiagrele &#8211; bugpiper, Nov.2017"},"author":11,"comment_status":"open","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"yoast_head":"<title>Guardiagrele - bugpiper, Nov.2017 - Miranda Loves Travelling<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guardiagrele - bugpiper, Nov.2017 - Miranda Loves Travelling\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mirandalovestravelling.com\/es\/italia-abruzos\/guardiagrele-5-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Miranda Loves Travelling\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Guardiagrele-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/italia-abruzos\/guardiagrele-5-2\/\",\"url\":\"https:\/\/mirandalovestravelling.com\/es\/italia-abruzos\/guardiagrele-5-2\/\",\"name\":\"Guardiagrele - bugpiper, Nov.2017 - Miranda Loves Travelling\",\"isPartOf\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/#website\"},\"datePublished\":\"2018-02-06T10:13:38+00:00\",\"dateModified\":\"2018-02-06T10:13:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/italia-abruzos\/guardiagrele-5-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mirandalovestravelling.com\/es\/italia-abruzos\/guardiagrele-5-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/italia-abruzos\/guardiagrele-5-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mirandalovestravelling.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Italia\",\"item\":\"https:\/\/mirandalovestravelling.com\/es\/location\/italia-es\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Abruzos\",\"item\":\"https:\/\/mirandalovestravelling.com\/es\/location\/italia-es\/abruzos\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Italia, Abruzos\",\"item\":\"https:\/\/mirandalovestravelling.com\/es\/italia-abruzos\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Guardiagrele &#8211; bugpiper, Nov.2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/#website\",\"url\":\"https:\/\/mirandalovestravelling.com\/es\/\",\"name\":\"Miranda Loves Travelling\",\"description\":\"Mi diario de viaje\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mirandalovestravelling.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>","yoast_head_json":{"title":"Guardiagrele - bugpiper, Nov.2017 - Miranda Loves Travelling","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Guardiagrele - bugpiper, Nov.2017 - Miranda Loves Travelling","og_url":"https:\/\/mirandalovestravelling.com\/es\/italia-abruzos\/guardiagrele-5-2\/","og_site_name":"Miranda Loves Travelling","og_image":[{"width":960,"height":1440,"url":"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Guardiagrele-5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mirandalovestravelling.com\/es\/italia-abruzos\/guardiagrele-5-2\/","url":"https:\/\/mirandalovestravelling.com\/es\/italia-abruzos\/guardiagrele-5-2\/","name":"Guardiagrele - bugpiper, Nov.2017 - Miranda Loves Travelling","isPartOf":{"@id":"https:\/\/mirandalovestravelling.com\/es\/#website"},"datePublished":"2018-02-06T10:13:38+00:00","dateModified":"2018-02-06T10:13:38+00:00","breadcrumb":{"@id":"https:\/\/mirandalovestravelling.com\/es\/italia-abruzos\/guardiagrele-5-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mirandalovestravelling.com\/es\/italia-abruzos\/guardiagrele-5-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mirandalovestravelling.com\/es\/italia-abruzos\/guardiagrele-5-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mirandalovestravelling.com\/es\/"},{"@type":"ListItem","position":2,"name":"Italia","item":"https:\/\/mirandalovestravelling.com\/es\/location\/italia-es\/"},{"@type":"ListItem","position":3,"name":"Abruzos","item":"https:\/\/mirandalovestravelling.com\/es\/location\/italia-es\/abruzos\/"},{"@type":"ListItem","position":4,"name":"Italia, Abruzos","item":"https:\/\/mirandalovestravelling.com\/es\/italia-abruzos\/"},{"@type":"ListItem","position":5,"name":"Guardiagrele &#8211; bugpiper, Nov.2017"}]},{"@type":"WebSite","@id":"https:\/\/mirandalovestravelling.com\/es\/#website","url":"https:\/\/mirandalovestravelling.com\/es\/","name":"Miranda Loves Travelling","description":"Mi diario de viaje","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mirandalovestravelling.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Guardiagrele-5.jpg'><img width=\"960\" height=\"1440\" src=\"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Guardiagrele-5.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Guardiagrele-5.jpg 960w, https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Guardiagrele-5-768x1152.jpg 768w, https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Guardiagrele-5-336x504.jpg 336w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":960,"height":1440,"file":"2018\/01\/Guardiagrele-5.jpg","sizes":{"thumbnail":{"file":"Guardiagrele-5-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Guardiagrele-5-150x150.jpg"},"medium_large":{"file":"Guardiagrele-5-768x1152.jpg","width":768,"height":1152,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Guardiagrele-5-768x1152.jpg"},"mlt-medium":{"file":"Guardiagrele-5-336x504.jpg","width":336,"height":504,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Guardiagrele-5-336x504.jpg"},"mlt-small":{"file":"Guardiagrele-5-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Guardiagrele-5-80x60.jpg"},"full":{"file":"Guardiagrele-5.jpg","width":960,"height":1440,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Guardiagrele-5.jpg"}},"image_meta":{"aperture":"4.8","credit":"","camera":"NIKON 1 V2","caption":"","created_timestamp":"1510397943","copyright":"","focal_length":"19.2","iso":"320","shutter_speed":"0.008","title":"","orientation":"1","keywords":[]},"ShortPixel":{"type":"lossy","exifKept":"0","date":"2019-04-26 09:03:21","thumbsOpt":4,"thumbsOptList":["Guardiagrele-5-150x150.jpg","Guardiagrele-5-768x1152.jpg","Guardiagrele-5-336x504.jpg","Guardiagrele-5-80x60.jpg"],"excludeSizes":[],"retinasOpt":0},"ShortPixelImprovement":"66.96"},"post":173507,"source_url":"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Guardiagrele-5.jpg","_links":{"self":[{"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/media\/174432"}],"collection":[{"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/users\/11"}]}}