{"id":243003,"date":"2023-03-14T10:53:14","date_gmt":"2023-03-14T10:53:14","guid":{"rendered":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-15.jpg"},"modified":"2023-03-14T10:53:14","modified_gmt":"2023-03-14T10:53:14","slug":"barcelona-2022-15-2","status":"inherit","type":"attachment","link":"https:\/\/mirandalovestravelling.com\/es\/barcelona-2022-15-2\/","title":{"rendered":"Barcelona 2022 (15)"},"author":10,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"yoast_head":"<title>Barcelona 2022 (15) - Miranda Loves Travelling<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Barcelona 2022 (15) - Miranda Loves Travelling\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mirandalovestravelling.com\/es\/barcelona-2022-15-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Miranda Loves Travelling\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-15-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1314\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/barcelona-2022-15-2\/\",\"url\":\"https:\/\/mirandalovestravelling.com\/es\/barcelona-2022-15-2\/\",\"name\":\"Barcelona 2022 (15) - Miranda Loves Travelling\",\"isPartOf\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/#website\"},\"datePublished\":\"2023-03-14T10:53:14+00:00\",\"dateModified\":\"2023-03-14T10:53:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/barcelona-2022-15-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mirandalovestravelling.com\/es\/barcelona-2022-15-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/barcelona-2022-15-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mirandalovestravelling.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Barcelona 2022 (15)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/#website\",\"url\":\"https:\/\/mirandalovestravelling.com\/es\/\",\"name\":\"Miranda Loves Travelling\",\"description\":\"Mi diario de viaje\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mirandalovestravelling.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>","yoast_head_json":{"title":"Barcelona 2022 (15) - Miranda Loves Travelling","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Barcelona 2022 (15) - Miranda Loves Travelling","og_url":"https:\/\/mirandalovestravelling.com\/es\/barcelona-2022-15-2\/","og_site_name":"Miranda Loves Travelling","og_image":[{"width":1920,"height":1314,"url":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-15-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mirandalovestravelling.com\/es\/barcelona-2022-15-2\/","url":"https:\/\/mirandalovestravelling.com\/es\/barcelona-2022-15-2\/","name":"Barcelona 2022 (15) - Miranda Loves Travelling","isPartOf":{"@id":"https:\/\/mirandalovestravelling.com\/es\/#website"},"datePublished":"2023-03-14T10:53:14+00:00","dateModified":"2023-03-14T10:53:14+00:00","breadcrumb":{"@id":"https:\/\/mirandalovestravelling.com\/es\/barcelona-2022-15-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mirandalovestravelling.com\/es\/barcelona-2022-15-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mirandalovestravelling.com\/es\/barcelona-2022-15-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mirandalovestravelling.com\/es\/"},{"@type":"ListItem","position":2,"name":"Barcelona 2022 (15)"}]},{"@type":"WebSite","@id":"https:\/\/mirandalovestravelling.com\/es\/#website","url":"https:\/\/mirandalovestravelling.com\/es\/","name":"Miranda Loves Travelling","description":"Mi diario de viaje","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mirandalovestravelling.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-15-scaled.jpg'><img width=\"1920\" height=\"1314\" src=\"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-15-scaled.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-15-scaled.jpg 1920w, https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-15-768x526.jpg 768w, https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-15-1536x1051.jpg 1536w, https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-15-336x230.jpg 336w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":1314,"file":"2023\/03\/Barcelona-2022-15-scaled.jpg","filesize":65103,"sizes":{"thumbnail":{"file":"Barcelona-2022-15-150x150.jpg","width":150,"height":150,"filesize":3577,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-15-150x150.jpg"},"medium_large":{"file":"Barcelona-2022-15-768x526.jpg","width":768,"height":526,"filesize":26908,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-15-768x526.jpg"},"1536x1536":{"file":"Barcelona-2022-15-1536x1051.jpg","width":1536,"height":1051,"filesize":54029,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-15-1536x1051.jpg"},"2048x2048":{"file":"Barcelona-2022-15-2048x1402.jpg","width":1920,"height":1314,"filesize":64763,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-15-2048x1402.jpg"},"mlt-medium":{"file":"Barcelona-2022-15-336x230.jpg","width":336,"height":230,"filesize":12778,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-15-336x230.jpg"},"mlt-small":{"file":"Barcelona-2022-15-80x60.jpg","width":80,"height":60,"filesize":1729,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-15-80x60.jpg"},"full":{"file":"Barcelona-2022-15-scaled.jpg","width":1920,"height":1314,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-15-scaled.jpg"}},"image_meta":{"aperture":"5.3","credit":"","camera":"NIKON 1 V2","caption":"","created_timestamp":"1668266124","copyright":"","focal_length":"27.2","iso":"1800","shutter_speed":"0.033333333333333","title":"","orientation":"1","keywords":[]},"original_image":"Barcelona-2022-15.jpg"},"post":null,"source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-15-scaled.jpg","_links":{"self":[{"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/media\/243003"}],"collection":[{"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/users\/10"}]}}