{"id":243714,"date":"2023-05-03T11:07:15","date_gmt":"2023-05-03T11:07:15","guid":{"rendered":"https:\/\/mirandalovestravelling.com\/media\/2023\/05\/Merida-2022-11.jpg"},"modified":"2023-05-03T11:07:15","modified_gmt":"2023-05-03T11:07:15","slug":"merida-2022-11-2","status":"inherit","type":"attachment","link":"https:\/\/mirandalovestravelling.com\/es\/merida-2022-11-2\/","title":{"rendered":"Merida 2022 (11)"},"author":10,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"yoast_head":"<title>Merida 2022 (11) - Miranda Loves Travelling<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Merida 2022 (11) - Miranda Loves Travelling\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mirandalovestravelling.com\/es\/merida-2022-11-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Miranda Loves Travelling\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mirandalovestravelling.com\/media\/2023\/05\/Merida-2022-11-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1707\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/merida-2022-11-2\/\",\"url\":\"https:\/\/mirandalovestravelling.com\/es\/merida-2022-11-2\/\",\"name\":\"Merida 2022 (11) - Miranda Loves Travelling\",\"isPartOf\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/#website\"},\"datePublished\":\"2023-05-03T11:07:15+00:00\",\"dateModified\":\"2023-05-03T11:07:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/merida-2022-11-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mirandalovestravelling.com\/es\/merida-2022-11-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/merida-2022-11-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mirandalovestravelling.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Merida 2022 (11)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/#website\",\"url\":\"https:\/\/mirandalovestravelling.com\/es\/\",\"name\":\"Miranda Loves Travelling\",\"description\":\"Mi diario de viaje\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mirandalovestravelling.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>","yoast_head_json":{"title":"Merida 2022 (11) - Miranda Loves Travelling","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Merida 2022 (11) - Miranda Loves Travelling","og_url":"https:\/\/mirandalovestravelling.com\/es\/merida-2022-11-2\/","og_site_name":"Miranda Loves Travelling","og_image":[{"width":1707,"height":2560,"url":"https:\/\/mirandalovestravelling.com\/media\/2023\/05\/Merida-2022-11-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mirandalovestravelling.com\/es\/merida-2022-11-2\/","url":"https:\/\/mirandalovestravelling.com\/es\/merida-2022-11-2\/","name":"Merida 2022 (11) - Miranda Loves Travelling","isPartOf":{"@id":"https:\/\/mirandalovestravelling.com\/es\/#website"},"datePublished":"2023-05-03T11:07:15+00:00","dateModified":"2023-05-03T11:07:15+00:00","breadcrumb":{"@id":"https:\/\/mirandalovestravelling.com\/es\/merida-2022-11-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mirandalovestravelling.com\/es\/merida-2022-11-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mirandalovestravelling.com\/es\/merida-2022-11-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mirandalovestravelling.com\/es\/"},{"@type":"ListItem","position":2,"name":"Merida 2022 (11)"}]},{"@type":"WebSite","@id":"https:\/\/mirandalovestravelling.com\/es\/#website","url":"https:\/\/mirandalovestravelling.com\/es\/","name":"Miranda Loves Travelling","description":"Mi diario de viaje","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mirandalovestravelling.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/mirandalovestravelling.com\/media\/2023\/05\/Merida-2022-11-scaled.jpg'><img width=\"1707\" height=\"2560\" src=\"https:\/\/mirandalovestravelling.com\/media\/2023\/05\/Merida-2022-11-scaled.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/mirandalovestravelling.com\/media\/2023\/05\/Merida-2022-11-scaled.jpg 1707w, https:\/\/mirandalovestravelling.com\/media\/2023\/05\/Merida-2022-11-768x1152.jpg 768w, https:\/\/mirandalovestravelling.com\/media\/2023\/05\/Merida-2022-11-1024x1536.jpg 1024w, https:\/\/mirandalovestravelling.com\/media\/2023\/05\/Merida-2022-11-1365x2048.jpg 1365w, https:\/\/mirandalovestravelling.com\/media\/2023\/05\/Merida-2022-11-336x504.jpg 336w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1707,"height":2560,"file":"2023\/05\/Merida-2022-11-scaled.jpg","filesize":216630,"sizes":{"thumbnail":{"file":"Merida-2022-11-150x150.jpg","width":150,"height":150,"filesize":5871,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/05\/Merida-2022-11-150x150.jpg"},"medium_large":{"file":"Merida-2022-11-768x1152.jpg","width":768,"height":1152,"filesize":91855,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/05\/Merida-2022-11-768x1152.jpg"},"1536x1536":{"file":"Merida-2022-11-1024x1536.jpg","width":1024,"height":1536,"filesize":101652,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/05\/Merida-2022-11-1024x1536.jpg"},"2048x2048":{"file":"Merida-2022-11-1365x2048.jpg","width":1365,"height":2048,"filesize":153240,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/05\/Merida-2022-11-1365x2048.jpg"},"mlt-medium":{"file":"Merida-2022-11-336x504.jpg","width":336,"height":504,"filesize":33554,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/05\/Merida-2022-11-336x504.jpg"},"mlt-small":{"file":"Merida-2022-11-80x60.jpg","width":80,"height":60,"filesize":1722,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/05\/Merida-2022-11-80x60.jpg"},"full":{"file":"Merida-2022-11-scaled.jpg","width":1707,"height":2560,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/05\/Merida-2022-11-scaled.jpg"}},"image_meta":{"aperture":"6.3","credit":"","camera":"NIKON D5600","caption":"","created_timestamp":"1672231066","copyright":"","focal_length":"26","iso":"100","shutter_speed":"0.00625","title":"","orientation":1,"keywords":[]},"original_image":"Merida-2022-11.jpg"},"post":null,"source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/05\/Merida-2022-11-scaled.jpg","_links":{"self":[{"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/media\/243714"}],"collection":[{"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/users\/10"}]}}