{"id":136638,"date":"2017-03-22T16:40:43","date_gmt":"2017-03-22T16:40:43","guid":{"rendered":"https:\/\/mirandalovestravelling.com\/photogallery\/italia-es\/colombia-barichara\/"},"modified":"2018-03-17T17:37:17","modified_gmt":"2018-03-17T17:37:17","slug":"colombia-barichara","status":"publish","type":"post","link":"https:\/\/mirandalovestravelling.com\/es\/colombia-barichara\/","title":{"rendered":"Colombia, Barichara"},"content":{"rendered":"<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;<\/p>\n","protected":false},"author":11,"featured_media":136640,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"categories":[1528,1527],"tags":[],"typology":[1917],"yoast_head":"<title>Colombia, Barichara<\/title>\n<meta name=\"description\" content=\"&nbsp;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/posts\/136638\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colombia, Barichara\" \/>\n<meta property=\"og:description\" content=\"&nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mirandalovestravelling.com\/es\/colombia-barichara\/\" \/>\n<meta property=\"og:site_name\" content=\"Miranda Loves Travelling\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-22T16:40:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-17T17:37:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mirandalovestravelling.com\/media\/2017\/03\/Barichara-13.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1271\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Miranda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/colombia-barichara\/\",\"url\":\"https:\/\/mirandalovestravelling.com\/es\/colombia-barichara\/\",\"name\":\"Colombia, Barichara\",\"isPartOf\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/#website\"},\"datePublished\":\"2017-03-22T16:40:43+00:00\",\"dateModified\":\"2018-03-17T17:37:17+00:00\",\"author\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/#\/schema\/person\/cd44a395321ccb8220a349214e003686\"},\"description\":\"&nbsp;\",\"breadcrumb\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/colombia-barichara\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mirandalovestravelling.com\/es\/colombia-barichara\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/colombia-barichara\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mirandalovestravelling.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Colombia\",\"item\":\"https:\/\/mirandalovestravelling.com\/es\/location\/colombia-es\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Barichara\",\"item\":\"https:\/\/mirandalovestravelling.com\/es\/location\/colombia-es\/barichara-es\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Colombia, Barichara\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/#website\",\"url\":\"https:\/\/mirandalovestravelling.com\/es\/\",\"name\":\"Miranda Loves Travelling\",\"description\":\"Mi diario de viaje\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mirandalovestravelling.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/#\/schema\/person\/cd44a395321ccb8220a349214e003686\",\"name\":\"Miranda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/mirandalovestravelling.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2020e5ef75dc730a8fbc1b656ea876e7?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2020e5ef75dc730a8fbc1b656ea876e7?s=96&r=g\",\"caption\":\"Miranda\"},\"description\":\"We are a couple who love travelling all over the world. Walking in the unknown towns, taking photos and eating local foods are the purpose of our life. When we are not travelling, we are always planning for the next journeys.\",\"sameAs\":[\"https:\/\/mirandalovestravelling.com\"]}]}<\/script>","yoast_head_json":{"title":"Colombia, Barichara","description":"&nbsp;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/posts\/136638","og_locale":"es_ES","og_type":"article","og_title":"Colombia, Barichara","og_description":"&nbsp;","og_url":"https:\/\/mirandalovestravelling.com\/es\/colombia-barichara\/","og_site_name":"Miranda Loves Travelling","article_published_time":"2017-03-22T16:40:43+00:00","article_modified_time":"2018-03-17T17:37:17+00:00","og_image":[{"width":1920,"height":1271,"url":"https:\/\/mirandalovestravelling.com\/media\/2017\/03\/Barichara-13.jpg","type":"image\/jpeg"}],"author":"Miranda","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":false},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mirandalovestravelling.com\/es\/colombia-barichara\/","url":"https:\/\/mirandalovestravelling.com\/es\/colombia-barichara\/","name":"Colombia, Barichara","isPartOf":{"@id":"https:\/\/mirandalovestravelling.com\/es\/#website"},"datePublished":"2017-03-22T16:40:43+00:00","dateModified":"2018-03-17T17:37:17+00:00","author":{"@id":"https:\/\/mirandalovestravelling.com\/es\/#\/schema\/person\/cd44a395321ccb8220a349214e003686"},"description":"&nbsp;","breadcrumb":{"@id":"https:\/\/mirandalovestravelling.com\/es\/colombia-barichara\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mirandalovestravelling.com\/es\/colombia-barichara\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mirandalovestravelling.com\/es\/colombia-barichara\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mirandalovestravelling.com\/es\/"},{"@type":"ListItem","position":2,"name":"Colombia","item":"https:\/\/mirandalovestravelling.com\/es\/location\/colombia-es\/"},{"@type":"ListItem","position":3,"name":"Barichara","item":"https:\/\/mirandalovestravelling.com\/es\/location\/colombia-es\/barichara-es\/"},{"@type":"ListItem","position":4,"name":"Colombia, Barichara"}]},{"@type":"WebSite","@id":"https:\/\/mirandalovestravelling.com\/es\/#website","url":"https:\/\/mirandalovestravelling.com\/es\/","name":"Miranda Loves Travelling","description":"Mi diario de viaje","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mirandalovestravelling.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/mirandalovestravelling.com\/es\/#\/schema\/person\/cd44a395321ccb8220a349214e003686","name":"Miranda","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mirandalovestravelling.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2020e5ef75dc730a8fbc1b656ea876e7?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2020e5ef75dc730a8fbc1b656ea876e7?s=96&r=g","caption":"Miranda"},"description":"We are a couple who love travelling all over the world. Walking in the unknown towns, taking photos and eating local foods are the purpose of our life. When we are not travelling, we are always planning for the next journeys.","sameAs":["https:\/\/mirandalovestravelling.com"]}]}},"_links":{"self":[{"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/posts\/136638"}],"collection":[{"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/comments?post=136638"}],"version-history":[{"count":0,"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/posts\/136638\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/media\/136640"}],"wp:attachment":[{"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/media?parent=136638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/categories?post=136638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/tags?post=136638"},{"taxonomy":"typology","embeddable":true,"href":"https:\/\/mirandalovestravelling.com\/es\/wp-json\/wp\/v2\/typology?post=136638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}