{"id":109000,"date":"2016-08-12T08:29:08","date_gmt":"2016-08-12T08:29:08","guid":{"rendered":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Bran-7.jpg"},"modified":"2016-08-12T08:29:08","modified_gmt":"2016-08-12T08:29:08","slug":"bran-7-2-2","status":"inherit","type":"attachment","link":"https:\/\/mirandalovestravelling.com\/it\/romania-bran\/bran-7-2-2\/","title":{"rendered":"Romania, Bran &#8211; uova di Pasqua, apr. 2014"},"author":11,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"yoast_head":"<title>Romania, Bran - uova di Pasqua, apr. 2014 - Miranda Loves Travelling<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Romania, Bran - uova di Pasqua, apr. 2014 - Miranda Loves Travelling\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mirandalovestravelling.com\/it\/romania-bran\/bran-7-2-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Miranda Loves Travelling\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Bran-7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"662\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/romania-bran\/bran-7-2-2\/\",\"url\":\"https:\/\/mirandalovestravelling.com\/it\/romania-bran\/bran-7-2-2\/\",\"name\":\"Romania, Bran - uova di Pasqua, apr. 2014 - Miranda Loves Travelling\",\"isPartOf\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/#website\"},\"datePublished\":\"2016-08-12T08:29:08+00:00\",\"dateModified\":\"2016-08-12T08:29:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/romania-bran\/bran-7-2-2\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mirandalovestravelling.com\/it\/romania-bran\/bran-7-2-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/romania-bran\/bran-7-2-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mirandalovestravelling.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Romania\",\"item\":\"https:\/\/mirandalovestravelling.com\/it\/location\/romania-it\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bran\",\"item\":\"https:\/\/mirandalovestravelling.com\/it\/location\/romania-it\/bran-it\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Romania Bran\",\"item\":\"https:\/\/mirandalovestravelling.com\/it\/romania-bran\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Romania, Bran &#8211; uova di Pasqua, apr. 2014\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/#website\",\"url\":\"https:\/\/mirandalovestravelling.com\/it\/\",\"name\":\"Miranda Loves Travelling\",\"description\":\"My Travel Diary\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mirandalovestravelling.com\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"}]}<\/script>","yoast_head_json":{"title":"Romania, Bran - uova di Pasqua, apr. 2014 - Miranda Loves Travelling","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Romania, Bran - uova di Pasqua, apr. 2014 - Miranda Loves Travelling","og_url":"https:\/\/mirandalovestravelling.com\/it\/romania-bran\/bran-7-2-2\/","og_site_name":"Miranda Loves Travelling","og_image":[{"width":1000,"height":662,"url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Bran-7.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mirandalovestravelling.com\/it\/romania-bran\/bran-7-2-2\/","url":"https:\/\/mirandalovestravelling.com\/it\/romania-bran\/bran-7-2-2\/","name":"Romania, Bran - uova di Pasqua, apr. 2014 - Miranda Loves Travelling","isPartOf":{"@id":"https:\/\/mirandalovestravelling.com\/it\/#website"},"datePublished":"2016-08-12T08:29:08+00:00","dateModified":"2016-08-12T08:29:08+00:00","breadcrumb":{"@id":"https:\/\/mirandalovestravelling.com\/it\/romania-bran\/bran-7-2-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mirandalovestravelling.com\/it\/romania-bran\/bran-7-2-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mirandalovestravelling.com\/it\/romania-bran\/bran-7-2-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mirandalovestravelling.com\/it\/"},{"@type":"ListItem","position":2,"name":"Romania","item":"https:\/\/mirandalovestravelling.com\/it\/location\/romania-it\/"},{"@type":"ListItem","position":3,"name":"Bran","item":"https:\/\/mirandalovestravelling.com\/it\/location\/romania-it\/bran-it\/"},{"@type":"ListItem","position":4,"name":"Romania Bran","item":"https:\/\/mirandalovestravelling.com\/it\/romania-bran\/"},{"@type":"ListItem","position":5,"name":"Romania, Bran &#8211; uova di Pasqua, apr. 2014"}]},{"@type":"WebSite","@id":"https:\/\/mirandalovestravelling.com\/it\/#website","url":"https:\/\/mirandalovestravelling.com\/it\/","name":"Miranda Loves Travelling","description":"My Travel Diary","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mirandalovestravelling.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Bran-7.jpg'><img width=\"1000\" height=\"662\" src=\"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Bran-7.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Bran-7.jpg 1000w, https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Bran-7-768x508.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1000,"height":662,"file":"2016\/08\/Bran-7.jpg","sizes":{"thumbnail":{"file":"Bran-7-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Bran-7-150x150.jpg"},"medium_large":{"file":"Bran-7-768x508.jpg","width":768,"height":508,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Bran-7-768x508.jpg"},"mlt-medium":{"file":"Bran-7-326x245.jpg","width":326,"height":245,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Bran-7-326x245.jpg"},"mlt-small":{"file":"Bran-7-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Bran-7-80x60.jpg"},"full":{"file":"Bran-7.jpg","width":1000,"height":662,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Bran-7.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ShortPixel":{"type":"lossy","exifKept":"0","date":"2019-05-04 22:53:18","thumbsOpt":4,"thumbsOptList":["Bran-7-150x150.jpg","Bran-7-768x508.jpg","Bran-7-326x245.jpg","Bran-7-80x60.jpg"],"excludeSizes":[],"retinasOpt":0},"ShortPixelImprovement":"43.34"},"post":121414,"source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Bran-7.jpg","_links":{"self":[{"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/media\/109000"}],"collection":[{"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/users\/11"}]}}