{"id":117955,"date":"2016-08-12T13:28:59","date_gmt":"2016-08-12T13:28:59","guid":{"rendered":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Turkey-080.jpg"},"modified":"2019-03-13T21:25:32","modified_gmt":"2019-03-13T21:25:32","slug":"turkey-080-2-2","status":"inherit","type":"attachment","link":"https:\/\/mirandalovestravelling.com\/it\/turchia-istanbul\/turkey-080-2-2\/","title":{"rendered":"Il Topkapi di Istanbul"},"author":11,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"yoast_head":"<title>Il Topkapi di Istanbul - Miranda Loves Travelling<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Topkapi di Istanbul - Miranda Loves Travelling\" \/>\n<meta property=\"og:description\" content=\"Palazzo Topkapi di Istanbul\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mirandalovestravelling.com\/it\/turchia-istanbul\/turkey-080-2-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Miranda Loves Travelling\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-13T21:25:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Turkey-080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"662\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/turchia-istanbul\/turkey-080-2-2\/\",\"url\":\"https:\/\/mirandalovestravelling.com\/it\/turchia-istanbul\/turkey-080-2-2\/\",\"name\":\"Il Topkapi di Istanbul - Miranda Loves Travelling\",\"isPartOf\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/#website\"},\"datePublished\":\"2016-08-12T13:28:59+00:00\",\"dateModified\":\"2019-03-13T21:25:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/turchia-istanbul\/turkey-080-2-2\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mirandalovestravelling.com\/it\/turchia-istanbul\/turkey-080-2-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/turchia-istanbul\/turkey-080-2-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mirandalovestravelling.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Turchia\",\"item\":\"https:\/\/mirandalovestravelling.com\/it\/location\/turchia\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Istanbul\",\"item\":\"https:\/\/mirandalovestravelling.com\/it\/location\/turchia\/istanbul-it\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Turchia Istanbul\",\"item\":\"https:\/\/mirandalovestravelling.com\/it\/turchia-istanbul\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Il Topkapi di Istanbul\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/#website\",\"url\":\"https:\/\/mirandalovestravelling.com\/it\/\",\"name\":\"Miranda Loves Travelling\",\"description\":\"My Travel Diary\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mirandalovestravelling.com\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"}]}<\/script>","yoast_head_json":{"title":"Il Topkapi di Istanbul - Miranda Loves Travelling","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Il Topkapi di Istanbul - Miranda Loves Travelling","og_description":"Palazzo Topkapi di Istanbul","og_url":"https:\/\/mirandalovestravelling.com\/it\/turchia-istanbul\/turkey-080-2-2\/","og_site_name":"Miranda Loves Travelling","article_modified_time":"2019-03-13T21:25:32+00:00","og_image":[{"width":662,"height":1000,"url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Turkey-080.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mirandalovestravelling.com\/it\/turchia-istanbul\/turkey-080-2-2\/","url":"https:\/\/mirandalovestravelling.com\/it\/turchia-istanbul\/turkey-080-2-2\/","name":"Il Topkapi di Istanbul - Miranda Loves Travelling","isPartOf":{"@id":"https:\/\/mirandalovestravelling.com\/it\/#website"},"datePublished":"2016-08-12T13:28:59+00:00","dateModified":"2019-03-13T21:25:32+00:00","breadcrumb":{"@id":"https:\/\/mirandalovestravelling.com\/it\/turchia-istanbul\/turkey-080-2-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mirandalovestravelling.com\/it\/turchia-istanbul\/turkey-080-2-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mirandalovestravelling.com\/it\/turchia-istanbul\/turkey-080-2-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mirandalovestravelling.com\/it\/"},{"@type":"ListItem","position":2,"name":"Turchia","item":"https:\/\/mirandalovestravelling.com\/it\/location\/turchia\/"},{"@type":"ListItem","position":3,"name":"Istanbul","item":"https:\/\/mirandalovestravelling.com\/it\/location\/turchia\/istanbul-it\/"},{"@type":"ListItem","position":4,"name":"Turchia Istanbul","item":"https:\/\/mirandalovestravelling.com\/it\/turchia-istanbul\/"},{"@type":"ListItem","position":5,"name":"Il Topkapi di Istanbul"}]},{"@type":"WebSite","@id":"https:\/\/mirandalovestravelling.com\/it\/#website","url":"https:\/\/mirandalovestravelling.com\/it\/","name":"Miranda Loves Travelling","description":"My Travel Diary","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mirandalovestravelling.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Turkey-080.jpg'><img width=\"662\" height=\"1000\" src=\"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Turkey-080.jpg\" class=\"attachment-medium size-medium\" alt=\"topkapi-istanbul-turchia\" decoding=\"async\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Palazzo Topkapi di Istanbul<\/p>\n"},"alt_text":"topkapi-istanbul-turchia","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":662,"height":1000,"file":"2016\/08\/Turkey-080.jpg","sizes":{"thumbnail":{"file":"Turkey-080-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Turkey-080-150x150.jpg"},"mlt-medium":{"file":"Turkey-080-326x245.jpg","width":326,"height":245,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Turkey-080-326x245.jpg"},"mlt-small":{"file":"Turkey-080-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Turkey-080-80x60.jpg"},"full":{"file":"Turkey-080.jpg","width":662,"height":1000,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Turkey-080.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ShortPixel":{"type":"lossy","exifKept":"0","date":"2019-05-05 18:47:15","thumbsOpt":3,"thumbsOptList":["Turkey-080-150x150.jpg","Turkey-080-326x245.jpg","Turkey-080-80x60.jpg"],"excludeSizes":[],"retinasOpt":0},"ShortPixelImprovement":"34.37"},"post":121314,"source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Turkey-080.jpg","_links":{"self":[{"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/media\/117955"}],"collection":[{"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/users\/11"}]}}