{"id":136281,"date":"2017-06-14T16:09:04","date_gmt":"2017-06-14T16:09:04","guid":{"rendered":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Venezia-35.jpg"},"modified":"2017-06-14T16:09:04","modified_gmt":"2017-06-14T16:09:04","slug":"venezia-35-2","status":"inherit","type":"attachment","link":"https:\/\/mirandalovestravelling.com\/it\/italia-venezia\/venezia-35-2\/","title":{"rendered":"Venezia- (35)"},"author":11,"comment_status":"open","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"yoast_head":"<title>Venezia- (35) - Miranda Loves Travelling<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Venezia- (35) - Miranda Loves Travelling\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mirandalovestravelling.com\/it\/italia-venezia\/venezia-35-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Miranda Loves Travelling\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Venezia-35.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2414\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/italia-venezia\/venezia-35-2\/\",\"url\":\"https:\/\/mirandalovestravelling.com\/it\/italia-venezia\/venezia-35-2\/\",\"name\":\"Venezia- (35) - Miranda Loves Travelling\",\"isPartOf\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/#website\"},\"datePublished\":\"2017-06-14T16:09:04+00:00\",\"dateModified\":\"2017-06-14T16:09:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/italia-venezia\/venezia-35-2\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mirandalovestravelling.com\/it\/italia-venezia\/venezia-35-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/italia-venezia\/venezia-35-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mirandalovestravelling.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Italia\",\"item\":\"https:\/\/mirandalovestravelling.com\/it\/location\/italia\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Venezia\",\"item\":\"https:\/\/mirandalovestravelling.com\/it\/location\/italia\/venezia\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Italia Venezia\",\"item\":\"https:\/\/mirandalovestravelling.com\/it\/italia-venezia\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Venezia- (35)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/#website\",\"url\":\"https:\/\/mirandalovestravelling.com\/it\/\",\"name\":\"Miranda Loves Travelling\",\"description\":\"My Travel Diary\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mirandalovestravelling.com\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"}]}<\/script>","yoast_head_json":{"title":"Venezia- (35) - Miranda Loves Travelling","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Venezia- (35) - Miranda Loves Travelling","og_url":"https:\/\/mirandalovestravelling.com\/it\/italia-venezia\/venezia-35-2\/","og_site_name":"Miranda Loves Travelling","og_image":[{"width":1920,"height":2414,"url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Venezia-35.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mirandalovestravelling.com\/it\/italia-venezia\/venezia-35-2\/","url":"https:\/\/mirandalovestravelling.com\/it\/italia-venezia\/venezia-35-2\/","name":"Venezia- (35) - Miranda Loves Travelling","isPartOf":{"@id":"https:\/\/mirandalovestravelling.com\/it\/#website"},"datePublished":"2017-06-14T16:09:04+00:00","dateModified":"2017-06-14T16:09:04+00:00","breadcrumb":{"@id":"https:\/\/mirandalovestravelling.com\/it\/italia-venezia\/venezia-35-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mirandalovestravelling.com\/it\/italia-venezia\/venezia-35-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mirandalovestravelling.com\/it\/italia-venezia\/venezia-35-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mirandalovestravelling.com\/it\/"},{"@type":"ListItem","position":2,"name":"Italia","item":"https:\/\/mirandalovestravelling.com\/it\/location\/italia\/"},{"@type":"ListItem","position":3,"name":"Venezia","item":"https:\/\/mirandalovestravelling.com\/it\/location\/italia\/venezia\/"},{"@type":"ListItem","position":4,"name":"Italia Venezia","item":"https:\/\/mirandalovestravelling.com\/it\/italia-venezia\/"},{"@type":"ListItem","position":5,"name":"Venezia- (35)"}]},{"@type":"WebSite","@id":"https:\/\/mirandalovestravelling.com\/it\/#website","url":"https:\/\/mirandalovestravelling.com\/it\/","name":"Miranda Loves Travelling","description":"My Travel Diary","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mirandalovestravelling.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Venezia-35.jpg'><img width=\"1920\" height=\"2414\" src=\"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Venezia-35.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Venezia-35.jpg 1920w, https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Venezia-35-768x966.jpg 768w, https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Venezia-35-336x423.jpg 336w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":2414,"file":"2016\/08\/Venezia-35.jpg","sizes":{"thumbnail":{"file":"Venezia-35-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Venezia-35-150x150.jpg"},"medium_large":{"file":"Venezia-35-768x966.jpg","width":768,"height":966,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Venezia-35-768x966.jpg"},"mlt-medium":{"file":"Venezia-35-336x423.jpg","width":336,"height":423,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Venezia-35-336x423.jpg"},"mlt-small":{"file":"Venezia-35-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Venezia-35-80x60.jpg"},"full":{"file":"Venezia-35.jpg","width":1920,"height":2414,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Venezia-35.jpg"}},"image_meta":{"aperture":"2.2","credit":"","camera":"iPhone 6","caption":"","created_timestamp":"1491126047","copyright":"","focal_length":"4.15","iso":"40","shutter_speed":"0.01","title":"","orientation":"0","keywords":[]},"ShortPixel":{"type":"lossy","exifKept":"0","date":"2019-05-06 09:44:51","thumbsOpt":4,"thumbsOptList":["Venezia-35-150x150.jpg","Venezia-35-768x966.jpg","Venezia-35-336x423.jpg","Venezia-35-80x60.jpg"],"excludeSizes":[],"retinasOpt":0},"ShortPixelImprovement":"73.59"},"post":121277,"source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Venezia-35.jpg","_links":{"self":[{"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/media\/136281"}],"collection":[{"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/users\/11"}]}}