{"id":159654,"date":"2017-08-11T15:48:48","date_gmt":"2017-08-11T15:48:48","guid":{"rendered":"https:\/\/mirandalovestravelling.com\/media\/2017\/08\/Brno-45.jpg"},"modified":"2017-08-11T15:48:48","modified_gmt":"2017-08-11T15:48:48","slug":"brno-45-2","status":"inherit","type":"attachment","link":"https:\/\/mirandalovestravelling.com\/it\/repubblica-ceca-brno\/brno-45-2\/","title":{"rendered":"Brno (45)"},"author":11,"comment_status":"open","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"yoast_head":"<title>Brno (45) - Miranda Loves Travelling<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brno (45) - Miranda Loves Travelling\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mirandalovestravelling.com\/it\/repubblica-ceca-brno\/brno-45-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Miranda Loves Travelling\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mirandalovestravelling.com\/media\/2017\/08\/Brno-45.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/repubblica-ceca-brno\/brno-45-2\/\",\"url\":\"https:\/\/mirandalovestravelling.com\/it\/repubblica-ceca-brno\/brno-45-2\/\",\"name\":\"Brno (45) - Miranda Loves Travelling\",\"isPartOf\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/#website\"},\"datePublished\":\"2017-08-11T15:48:48+00:00\",\"dateModified\":\"2017-08-11T15:48:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/repubblica-ceca-brno\/brno-45-2\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mirandalovestravelling.com\/it\/repubblica-ceca-brno\/brno-45-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/repubblica-ceca-brno\/brno-45-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mirandalovestravelling.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Repubblica Ceca\",\"item\":\"https:\/\/mirandalovestravelling.com\/it\/location\/repubblica-ceca\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Brno\",\"item\":\"https:\/\/mirandalovestravelling.com\/it\/location\/repubblica-ceca\/brno-it\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Repubblica Ceca, Brno\",\"item\":\"https:\/\/mirandalovestravelling.com\/it\/repubblica-ceca-brno\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Brno (45)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/#website\",\"url\":\"https:\/\/mirandalovestravelling.com\/it\/\",\"name\":\"Miranda Loves Travelling\",\"description\":\"My Travel Diary\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mirandalovestravelling.com\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"}]}<\/script>","yoast_head_json":{"title":"Brno (45) - Miranda Loves Travelling","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Brno (45) - Miranda Loves Travelling","og_url":"https:\/\/mirandalovestravelling.com\/it\/repubblica-ceca-brno\/brno-45-2\/","og_site_name":"Miranda Loves Travelling","og_image":[{"width":960,"height":1440,"url":"https:\/\/mirandalovestravelling.com\/media\/2017\/08\/Brno-45.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mirandalovestravelling.com\/it\/repubblica-ceca-brno\/brno-45-2\/","url":"https:\/\/mirandalovestravelling.com\/it\/repubblica-ceca-brno\/brno-45-2\/","name":"Brno (45) - Miranda Loves Travelling","isPartOf":{"@id":"https:\/\/mirandalovestravelling.com\/it\/#website"},"datePublished":"2017-08-11T15:48:48+00:00","dateModified":"2017-08-11T15:48:48+00:00","breadcrumb":{"@id":"https:\/\/mirandalovestravelling.com\/it\/repubblica-ceca-brno\/brno-45-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mirandalovestravelling.com\/it\/repubblica-ceca-brno\/brno-45-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mirandalovestravelling.com\/it\/repubblica-ceca-brno\/brno-45-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mirandalovestravelling.com\/it\/"},{"@type":"ListItem","position":2,"name":"Repubblica Ceca","item":"https:\/\/mirandalovestravelling.com\/it\/location\/repubblica-ceca\/"},{"@type":"ListItem","position":3,"name":"Brno","item":"https:\/\/mirandalovestravelling.com\/it\/location\/repubblica-ceca\/brno-it\/"},{"@type":"ListItem","position":4,"name":"Repubblica Ceca, Brno","item":"https:\/\/mirandalovestravelling.com\/it\/repubblica-ceca-brno\/"},{"@type":"ListItem","position":5,"name":"Brno (45)"}]},{"@type":"WebSite","@id":"https:\/\/mirandalovestravelling.com\/it\/#website","url":"https:\/\/mirandalovestravelling.com\/it\/","name":"Miranda Loves Travelling","description":"My Travel Diary","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mirandalovestravelling.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/mirandalovestravelling.com\/media\/2017\/08\/Brno-45.jpg'><img width=\"960\" height=\"1440\" src=\"https:\/\/mirandalovestravelling.com\/media\/2017\/08\/Brno-45.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/mirandalovestravelling.com\/media\/2017\/08\/Brno-45.jpg 960w, https:\/\/mirandalovestravelling.com\/media\/2017\/08\/Brno-45-768x1152.jpg 768w, https:\/\/mirandalovestravelling.com\/media\/2017\/08\/Brno-45-336x504.jpg 336w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":960,"height":1440,"file":"2017\/08\/Brno-45.jpg","sizes":{"thumbnail":{"file":"Brno-45-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2017\/08\/Brno-45-150x150.jpg"},"medium_large":{"file":"Brno-45-768x1152.jpg","width":768,"height":1152,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2017\/08\/Brno-45-768x1152.jpg"},"mlt-medium":{"file":"Brno-45-336x504.jpg","width":336,"height":504,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2017\/08\/Brno-45-336x504.jpg"},"mlt-small":{"file":"Brno-45-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2017\/08\/Brno-45-80x60.jpg"},"full":{"file":"Brno-45.jpg","width":960,"height":1440,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2017\/08\/Brno-45.jpg"}},"image_meta":{"aperture":"9","credit":"www.mirandalovestravelling.jp","camera":"Canon EOS 1100D","caption":"","created_timestamp":"1495875035","copyright":"","focal_length":"51","iso":"200","shutter_speed":"0.004","title":"","orientation":"1","keywords":[]},"ShortPixel":{"type":"lossy","exifKept":"0","date":"2019-04-28 11:20:50","thumbsOpt":4,"thumbsOptList":["Brno-45-150x150.jpg","Brno-45-768x1152.jpg","Brno-45-336x504.jpg","Brno-45-80x60.jpg"],"excludeSizes":[],"retinasOpt":0},"ShortPixelImprovement":"39.71"},"post":159563,"source_url":"https:\/\/mirandalovestravelling.com\/media\/2017\/08\/Brno-45.jpg","_links":{"self":[{"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/media\/159654"}],"collection":[{"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/users\/11"}]}}