{"id":174539,"date":"2018-02-07T10:08:17","date_gmt":"2018-02-07T10:08:17","guid":{"rendered":"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Guardiagrele-27.jpg"},"modified":"2018-02-07T10:08:17","modified_gmt":"2018-02-07T10:08:17","slug":"guardiagrele-27-2","status":"inherit","type":"attachment","link":"https:\/\/mirandalovestravelling.com\/it\/italia-abruzzo\/guardiagrele-27-2\/","title":{"rendered":"Guardiagrele, Santa Maria Maggiore &#8211; chapel, Nov.2017"},"author":11,"comment_status":"open","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"yoast_head":"<title>Guardiagrele, Santa Maria Maggiore - chapel, Nov.2017 - Miranda Loves Travelling<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guardiagrele, Santa Maria Maggiore - chapel, Nov.2017 - Miranda Loves Travelling\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mirandalovestravelling.com\/it\/italia-abruzzo\/guardiagrele-27-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Miranda Loves Travelling\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Guardiagrele-27.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/italia-abruzzo\/guardiagrele-27-2\/\",\"url\":\"https:\/\/mirandalovestravelling.com\/it\/italia-abruzzo\/guardiagrele-27-2\/\",\"name\":\"Guardiagrele, Santa Maria Maggiore - chapel, Nov.2017 - Miranda Loves Travelling\",\"isPartOf\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/#website\"},\"datePublished\":\"2018-02-07T10:08:17+00:00\",\"dateModified\":\"2018-02-07T10:08:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/italia-abruzzo\/guardiagrele-27-2\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mirandalovestravelling.com\/it\/italia-abruzzo\/guardiagrele-27-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/italia-abruzzo\/guardiagrele-27-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mirandalovestravelling.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Italia\",\"item\":\"https:\/\/mirandalovestravelling.com\/it\/location\/italia\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Abruzzo\",\"item\":\"https:\/\/mirandalovestravelling.com\/it\/location\/italia\/abruzzo-it\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Italia, Abruzzo\",\"item\":\"https:\/\/mirandalovestravelling.com\/it\/italia-abruzzo\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Guardiagrele, Santa Maria Maggiore &#8211; chapel, Nov.2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/#website\",\"url\":\"https:\/\/mirandalovestravelling.com\/it\/\",\"name\":\"Miranda Loves Travelling\",\"description\":\"My Travel Diary\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mirandalovestravelling.com\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"}]}<\/script>","yoast_head_json":{"title":"Guardiagrele, Santa Maria Maggiore - chapel, Nov.2017 - Miranda Loves Travelling","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Guardiagrele, Santa Maria Maggiore - chapel, Nov.2017 - Miranda Loves Travelling","og_url":"https:\/\/mirandalovestravelling.com\/it\/italia-abruzzo\/guardiagrele-27-2\/","og_site_name":"Miranda Loves Travelling","og_image":[{"width":1920,"height":1280,"url":"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Guardiagrele-27.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mirandalovestravelling.com\/it\/italia-abruzzo\/guardiagrele-27-2\/","url":"https:\/\/mirandalovestravelling.com\/it\/italia-abruzzo\/guardiagrele-27-2\/","name":"Guardiagrele, Santa Maria Maggiore - chapel, Nov.2017 - Miranda Loves Travelling","isPartOf":{"@id":"https:\/\/mirandalovestravelling.com\/it\/#website"},"datePublished":"2018-02-07T10:08:17+00:00","dateModified":"2018-02-07T10:08:17+00:00","breadcrumb":{"@id":"https:\/\/mirandalovestravelling.com\/it\/italia-abruzzo\/guardiagrele-27-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mirandalovestravelling.com\/it\/italia-abruzzo\/guardiagrele-27-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mirandalovestravelling.com\/it\/italia-abruzzo\/guardiagrele-27-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mirandalovestravelling.com\/it\/"},{"@type":"ListItem","position":2,"name":"Italia","item":"https:\/\/mirandalovestravelling.com\/it\/location\/italia\/"},{"@type":"ListItem","position":3,"name":"Abruzzo","item":"https:\/\/mirandalovestravelling.com\/it\/location\/italia\/abruzzo-it\/"},{"@type":"ListItem","position":4,"name":"Italia, Abruzzo","item":"https:\/\/mirandalovestravelling.com\/it\/italia-abruzzo\/"},{"@type":"ListItem","position":5,"name":"Guardiagrele, Santa Maria Maggiore &#8211; chapel, Nov.2017"}]},{"@type":"WebSite","@id":"https:\/\/mirandalovestravelling.com\/it\/#website","url":"https:\/\/mirandalovestravelling.com\/it\/","name":"Miranda Loves Travelling","description":"My Travel Diary","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mirandalovestravelling.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Guardiagrele-27.jpg'><img width=\"1920\" height=\"1280\" src=\"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Guardiagrele-27.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Guardiagrele-27.jpg 1920w, https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Guardiagrele-27-768x512.jpg 768w, https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Guardiagrele-27-336x224.jpg 336w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":1280,"file":"2018\/01\/Guardiagrele-27.jpg","sizes":{"thumbnail":{"file":"Guardiagrele-27-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Guardiagrele-27-150x150.jpg"},"medium_large":{"file":"Guardiagrele-27-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Guardiagrele-27-768x512.jpg"},"mlt-medium":{"file":"Guardiagrele-27-336x224.jpg","width":336,"height":224,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Guardiagrele-27-336x224.jpg"},"mlt-small":{"file":"Guardiagrele-27-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Guardiagrele-27-80x60.jpg"},"full":{"file":"Guardiagrele-27.jpg","width":1920,"height":1280,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Guardiagrele-27.jpg"}},"image_meta":{"aperture":"4","credit":"Picasa","camera":"NIKON 1 V2","caption":"","created_timestamp":"1510414448","copyright":"","focal_length":"10","iso":"3200","shutter_speed":"0.076923076923077","title":"","orientation":"0","keywords":["Abruzzo"]},"ShortPixel":{"type":"lossy","exifKept":"0","date":"2019-04-26 08:56:51","thumbsOpt":4,"thumbsOptList":["Guardiagrele-27-150x150.jpg","Guardiagrele-27-768x512.jpg","Guardiagrele-27-336x224.jpg","Guardiagrele-27-80x60.jpg"],"excludeSizes":[],"retinasOpt":0},"ShortPixelImprovement":"76.38"},"post":173506,"source_url":"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Guardiagrele-27.jpg","_links":{"self":[{"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/media\/174539"}],"collection":[{"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/users\/11"}]}}