{"id":236056,"date":"2022-03-30T14:22:54","date_gmt":"2022-03-30T14:22:54","guid":{"rendered":"https:\/\/mirandalovestravelling.com\/media\/2022\/03\/Sintra-2021-10.jpg"},"modified":"2022-03-30T14:22:54","modified_gmt":"2022-03-30T14:22:54","slug":"sintra-2021-10-2","status":"inherit","type":"attachment","link":"https:\/\/mirandalovestravelling.com\/it\/eccentrico-palacio-da-pena\/sintra-2021-10-2\/","title":{"rendered":"Sintra 2021 (10)"},"author":10,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"yoast_head":"<title>Sintra 2021 (10) - Miranda Loves Travelling<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sintra 2021 (10) - Miranda Loves Travelling\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mirandalovestravelling.com\/it\/eccentrico-palacio-da-pena\/sintra-2021-10-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Miranda Loves Travelling\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mirandalovestravelling.com\/media\/2022\/03\/Sintra-2021-10-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/eccentrico-palacio-da-pena\/sintra-2021-10-2\/\",\"url\":\"https:\/\/mirandalovestravelling.com\/it\/eccentrico-palacio-da-pena\/sintra-2021-10-2\/\",\"name\":\"Sintra 2021 (10) - Miranda Loves Travelling\",\"isPartOf\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/#website\"},\"datePublished\":\"2022-03-30T14:22:54+00:00\",\"dateModified\":\"2022-03-30T14:22:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/eccentrico-palacio-da-pena\/sintra-2021-10-2\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mirandalovestravelling.com\/it\/eccentrico-palacio-da-pena\/sintra-2021-10-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/eccentrico-palacio-da-pena\/sintra-2021-10-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mirandalovestravelling.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sintra 2021 (10)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/#website\",\"url\":\"https:\/\/mirandalovestravelling.com\/it\/\",\"name\":\"Miranda Loves Travelling\",\"description\":\"My Travel Diary\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mirandalovestravelling.com\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"}]}<\/script>","yoast_head_json":{"title":"Sintra 2021 (10) - Miranda Loves Travelling","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Sintra 2021 (10) - Miranda Loves Travelling","og_url":"https:\/\/mirandalovestravelling.com\/it\/eccentrico-palacio-da-pena\/sintra-2021-10-2\/","og_site_name":"Miranda Loves Travelling","og_image":[{"width":1920,"height":1280,"url":"https:\/\/mirandalovestravelling.com\/media\/2022\/03\/Sintra-2021-10-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mirandalovestravelling.com\/it\/eccentrico-palacio-da-pena\/sintra-2021-10-2\/","url":"https:\/\/mirandalovestravelling.com\/it\/eccentrico-palacio-da-pena\/sintra-2021-10-2\/","name":"Sintra 2021 (10) - Miranda Loves Travelling","isPartOf":{"@id":"https:\/\/mirandalovestravelling.com\/it\/#website"},"datePublished":"2022-03-30T14:22:54+00:00","dateModified":"2022-03-30T14:22:54+00:00","breadcrumb":{"@id":"https:\/\/mirandalovestravelling.com\/it\/eccentrico-palacio-da-pena\/sintra-2021-10-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mirandalovestravelling.com\/it\/eccentrico-palacio-da-pena\/sintra-2021-10-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mirandalovestravelling.com\/it\/eccentrico-palacio-da-pena\/sintra-2021-10-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mirandalovestravelling.com\/it\/"},{"@type":"ListItem","position":2,"name":"Sintra 2021 (10)"}]},{"@type":"WebSite","@id":"https:\/\/mirandalovestravelling.com\/it\/#website","url":"https:\/\/mirandalovestravelling.com\/it\/","name":"Miranda Loves Travelling","description":"My Travel Diary","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mirandalovestravelling.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/mirandalovestravelling.com\/media\/2022\/03\/Sintra-2021-10-scaled.jpg'><img width=\"1920\" height=\"1280\" src=\"https:\/\/mirandalovestravelling.com\/media\/2022\/03\/Sintra-2021-10-scaled.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/mirandalovestravelling.com\/media\/2022\/03\/Sintra-2021-10-scaled.jpg 1920w, https:\/\/mirandalovestravelling.com\/media\/2022\/03\/Sintra-2021-10-768x512.jpg 768w, https:\/\/mirandalovestravelling.com\/media\/2022\/03\/Sintra-2021-10-1536x1024.jpg 1536w, https:\/\/mirandalovestravelling.com\/media\/2022\/03\/Sintra-2021-10-2048x1365.jpg 2048w, https:\/\/mirandalovestravelling.com\/media\/2022\/03\/Sintra-2021-10-336x224.jpg 336w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":1280,"file":"2022\/03\/Sintra-2021-10-scaled.jpg","sizes":{"thumbnail":{"file":"Sintra-2021-10-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2022\/03\/Sintra-2021-10-150x150.jpg"},"medium_large":{"file":"Sintra-2021-10-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2022\/03\/Sintra-2021-10-768x512.jpg"},"1536x1536":{"file":"Sintra-2021-10-1536x1024.jpg","width":1536,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2022\/03\/Sintra-2021-10-1536x1024.jpg"},"2048x2048":{"file":"Sintra-2021-10-2048x1365.jpg","width":2048,"height":1365,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2022\/03\/Sintra-2021-10-2048x1365.jpg"},"mlt-medium":{"file":"Sintra-2021-10-336x224.jpg","width":336,"height":224,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2022\/03\/Sintra-2021-10-336x224.jpg"},"mlt-small":{"file":"Sintra-2021-10-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2022\/03\/Sintra-2021-10-80x60.jpg"},"full":{"file":"Sintra-2021-10-scaled.jpg","width":1920,"height":1280,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2022\/03\/Sintra-2021-10-scaled.jpg"}},"image_meta":{"aperture":"4.5","credit":"","camera":"NIKON D5600","caption":"","created_timestamp":"1640612394","copyright":"","focal_length":"21","iso":"100","shutter_speed":"0.01","title":"","orientation":"1","keywords":[]},"original_image":"Sintra-2021-10.jpg","ShortPixel":{"type":"lossy","exifKept":"0","date":"2022-03-30 14:49:57","thumbsOpt":7,"thumbsOptList":["Sintra-2021-10.jpg","Sintra-2021-10-150x150.jpg","Sintra-2021-10-768x512.jpg","Sintra-2021-10-1536x1024.jpg","Sintra-2021-10-2048x1365.jpg","Sintra-2021-10-336x224.jpg","Sintra-2021-10-80x60.jpg"],"excludeSizes":[],"retinasOpt":0},"ShortPixelImprovement":"95.7"},"post":239030,"source_url":"https:\/\/mirandalovestravelling.com\/media\/2022\/03\/Sintra-2021-10-scaled.jpg","_links":{"self":[{"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/media\/236056"}],"collection":[{"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/users\/10"}]}}