{"id":242981,"date":"2023-03-14T10:52:41","date_gmt":"2023-03-14T10:52:41","guid":{"rendered":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-10.jpg"},"modified":"2023-09-21T18:45:52","modified_gmt":"2023-09-21T18:45:52","slug":"barcelona-2022-10-2","status":"inherit","type":"attachment","link":"https:\/\/mirandalovestravelling.com\/it\/barcelona-2022-10-2\/","title":{"rendered":"Barcelona"},"author":10,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"Relevanssi image attachment filter Relevanssi index exclude"},"yoast_head":"<title>Barcelona - Miranda Loves Travelling<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Barcelona - Miranda Loves Travelling\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mirandalovestravelling.com\/it\/barcelona-2022-10-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Miranda Loves Travelling\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-21T18:45:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-10-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/barcelona-2022-10-2\/\",\"url\":\"https:\/\/mirandalovestravelling.com\/it\/barcelona-2022-10-2\/\",\"name\":\"Barcelona - Miranda Loves Travelling\",\"isPartOf\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/#website\"},\"datePublished\":\"2023-03-14T10:52:41+00:00\",\"dateModified\":\"2023-09-21T18:45:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/barcelona-2022-10-2\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mirandalovestravelling.com\/it\/barcelona-2022-10-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/barcelona-2022-10-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mirandalovestravelling.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Barcelona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/#website\",\"url\":\"https:\/\/mirandalovestravelling.com\/it\/\",\"name\":\"Miranda Loves Travelling\",\"description\":\"My Travel Diary\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mirandalovestravelling.com\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"}]}<\/script>","yoast_head_json":{"title":"Barcelona - Miranda Loves Travelling","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Barcelona - Miranda Loves Travelling","og_url":"https:\/\/mirandalovestravelling.com\/it\/barcelona-2022-10-2\/","og_site_name":"Miranda Loves Travelling","article_modified_time":"2023-09-21T18:45:52+00:00","og_image":[{"width":1920,"height":1272,"url":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-10-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mirandalovestravelling.com\/it\/barcelona-2022-10-2\/","url":"https:\/\/mirandalovestravelling.com\/it\/barcelona-2022-10-2\/","name":"Barcelona - Miranda Loves Travelling","isPartOf":{"@id":"https:\/\/mirandalovestravelling.com\/it\/#website"},"datePublished":"2023-03-14T10:52:41+00:00","dateModified":"2023-09-21T18:45:52+00:00","breadcrumb":{"@id":"https:\/\/mirandalovestravelling.com\/it\/barcelona-2022-10-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mirandalovestravelling.com\/it\/barcelona-2022-10-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mirandalovestravelling.com\/it\/barcelona-2022-10-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mirandalovestravelling.com\/it\/"},{"@type":"ListItem","position":2,"name":"Barcelona"}]},{"@type":"WebSite","@id":"https:\/\/mirandalovestravelling.com\/it\/#website","url":"https:\/\/mirandalovestravelling.com\/it\/","name":"Miranda Loves Travelling","description":"My Travel Diary","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mirandalovestravelling.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-10-scaled.jpg'><img width=\"1920\" height=\"1272\" src=\"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-10-scaled.jpg\" class=\"attachment-medium size-medium\" alt=\"Casa Batll\u00f2 un balcone particolare\" decoding=\"async\" srcset=\"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-10-scaled.jpg 1920w, https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-10-768x509.jpg 768w, https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-10-1536x1017.jpg 1536w, https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-10-336x223.jpg 336w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Casa Batll\u00f2 un balcone particolare","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":1272,"file":"2023\/03\/Barcelona-2022-10-scaled.jpg","filesize":135925,"sizes":{"thumbnail":{"file":"Barcelona-2022-10-150x150.jpg","width":150,"height":150,"filesize":4944,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-10-150x150.jpg"},"medium_large":{"file":"Barcelona-2022-10-768x509.jpg","width":768,"height":509,"filesize":57204,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-10-768x509.jpg"},"1536x1536":{"file":"Barcelona-2022-10-1536x1017.jpg","width":1536,"height":1017,"filesize":96083,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-10-1536x1017.jpg"},"2048x2048":{"file":"Barcelona-2022-10-2048x1356.jpg","width":1920,"height":1271,"filesize":134610,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-10-2048x1356.jpg"},"mlt-medium":{"file":"Barcelona-2022-10-336x223.jpg","width":336,"height":223,"filesize":17762,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-10-336x223.jpg"},"mlt-small":{"file":"Barcelona-2022-10-80x60.jpg","width":80,"height":60,"filesize":1477,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-10-80x60.jpg"},"full":{"file":"Barcelona-2022-10-scaled.jpg","width":1920,"height":1272,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-10-scaled.jpg"}},"image_meta":{"aperture":"5.6","credit":"","camera":"NIKON D5100","caption":"","created_timestamp":"1668269127","copyright":"","focal_length":"122","iso":"100","shutter_speed":"0.008","title":"","orientation":"1","keywords":[]},"original_image":"Barcelona-2022-10.jpg"},"post":null,"source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-10-scaled.jpg","_links":{"self":[{"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/media\/242981"}],"collection":[{"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/users\/10"}]}}