{"id":70577,"date":"2016-08-09T09:40:36","date_gmt":"2016-08-09T09:40:36","guid":{"rendered":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/cuba-havana16.jpg"},"modified":"2016-08-09T09:40:36","modified_gmt":"2016-08-09T09:40:36","slug":"cuba-havana16-2","status":"inherit","type":"attachment","link":"https:\/\/mirandalovestravelling.com\/it\/cuba-havana\/cuba-havana16-2\/","title":{"rendered":"Cuba, L&#8217;Avana &#8211; corridoio, primavera 2010"},"author":11,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"yoast_head":"<title>Cuba, L&#039;Avana - corridoio, primavera 2010 - Miranda Loves Travelling<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuba, L&#039;Avana - corridoio, primavera 2010 - Miranda Loves Travelling\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mirandalovestravelling.com\/it\/cuba-havana\/cuba-havana16-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Miranda Loves Travelling\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/cuba-havana16.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"671\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/cuba-havana\/cuba-havana16-2\/\",\"url\":\"https:\/\/mirandalovestravelling.com\/it\/cuba-havana\/cuba-havana16-2\/\",\"name\":\"Cuba, L'Avana - corridoio, primavera 2010 - Miranda Loves Travelling\",\"isPartOf\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/#website\"},\"datePublished\":\"2016-08-09T09:40:36+00:00\",\"dateModified\":\"2016-08-09T09:40:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/cuba-havana\/cuba-havana16-2\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mirandalovestravelling.com\/it\/cuba-havana\/cuba-havana16-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/cuba-havana\/cuba-havana16-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mirandalovestravelling.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuba Havana\",\"item\":\"https:\/\/mirandalovestravelling.com\/it\/cuba-havana\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cuba, L&#8217;Avana &#8211; corridoio, primavera 2010\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mirandalovestravelling.com\/it\/#website\",\"url\":\"https:\/\/mirandalovestravelling.com\/it\/\",\"name\":\"Miranda Loves Travelling\",\"description\":\"My Travel Diary\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mirandalovestravelling.com\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"}]}<\/script>","yoast_head_json":{"title":"Cuba, L'Avana - corridoio, primavera 2010 - Miranda Loves Travelling","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Cuba, L'Avana - corridoio, primavera 2010 - Miranda Loves Travelling","og_url":"https:\/\/mirandalovestravelling.com\/it\/cuba-havana\/cuba-havana16-2\/","og_site_name":"Miranda Loves Travelling","og_image":[{"width":1000,"height":671,"url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/cuba-havana16.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mirandalovestravelling.com\/it\/cuba-havana\/cuba-havana16-2\/","url":"https:\/\/mirandalovestravelling.com\/it\/cuba-havana\/cuba-havana16-2\/","name":"Cuba, L'Avana - corridoio, primavera 2010 - Miranda Loves Travelling","isPartOf":{"@id":"https:\/\/mirandalovestravelling.com\/it\/#website"},"datePublished":"2016-08-09T09:40:36+00:00","dateModified":"2016-08-09T09:40:36+00:00","breadcrumb":{"@id":"https:\/\/mirandalovestravelling.com\/it\/cuba-havana\/cuba-havana16-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mirandalovestravelling.com\/it\/cuba-havana\/cuba-havana16-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mirandalovestravelling.com\/it\/cuba-havana\/cuba-havana16-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mirandalovestravelling.com\/it\/"},{"@type":"ListItem","position":2,"name":"Cuba Havana","item":"https:\/\/mirandalovestravelling.com\/it\/cuba-havana\/"},{"@type":"ListItem","position":3,"name":"Cuba, L&#8217;Avana &#8211; corridoio, primavera 2010"}]},{"@type":"WebSite","@id":"https:\/\/mirandalovestravelling.com\/it\/#website","url":"https:\/\/mirandalovestravelling.com\/it\/","name":"Miranda Loves Travelling","description":"My Travel Diary","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mirandalovestravelling.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/mirandalovestravelling.com\/media\/2016\/08\/cuba-havana16.jpg'><img width=\"1000\" height=\"671\" src=\"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/cuba-havana16.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/cuba-havana16.jpg 1000w, https:\/\/mirandalovestravelling.com\/media\/2016\/08\/cuba-havana16-768x515.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1000,"height":671,"file":"2016\/08\/cuba-havana16.jpg","sizes":{"thumbnail":{"file":"cuba-havana16-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/cuba-havana16-150x150.jpg"},"medium_large":{"file":"cuba-havana16-768x515.jpg","width":768,"height":515,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/cuba-havana16-768x515.jpg"},"mlt-medium":{"file":"cuba-havana16-326x245.jpg","width":326,"height":245,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/cuba-havana16-326x245.jpg"},"mlt-small":{"file":"cuba-havana16-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/cuba-havana16-80x60.jpg"},"full":{"file":"cuba-havana16.jpg","width":1000,"height":671,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/cuba-havana16.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ShortPixel":{"type":"lossy","exifKept":"0","date":"2019-04-29 11:32:57","thumbsOpt":4,"thumbsOptList":["cuba-havana16-150x150.jpg","cuba-havana16-768x515.jpg","cuba-havana16-326x245.jpg","cuba-havana16-80x60.jpg"],"excludeSizes":[],"retinasOpt":0},"ShortPixelImprovement":"44.19"},"post":121652,"source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/cuba-havana16.jpg","_links":{"self":[{"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/media\/70577"}],"collection":[{"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/mirandalovestravelling.com\/it\/wp-json\/wp\/v2\/users\/11"}]}}