{"id":106761,"date":"2016-08-12T07:31:35","date_gmt":"2016-08-12T07:31:35","guid":{"rendered":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Malta_gozo-1.jpg"},"modified":"2016-08-12T07:31:35","modified_gmt":"2016-08-12T07:31:35","slug":"malta_gozo-1-2","status":"inherit","type":"attachment","link":"https:\/\/mirandalovestravelling.com\/ja\/%e3%83%9e%e3%83%ab%e3%82%bf%ef%bc%8d%e3%82%b4%e3%82%be%e5%b3%b6\/malta_gozo-1-2\/","title":{"rendered":"\u30de\u30eb\u30bf\u3001\u30b4\u30be\u5cf6\uff0d\u6e2f\u306e\u5149\u666f 2013\u5e742\u6708"},"author":11,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"yoast_head":"<title>\u30de\u30eb\u30bf\u3001\u30b4\u30be\u5cf6\uff0d\u6e2f\u306e\u5149\u666f 2013\u5e742\u6708 - Miranda Loves Travelling<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u30de\u30eb\u30bf\u3001\u30b4\u30be\u5cf6\uff0d\u6e2f\u306e\u5149\u666f 2013\u5e742\u6708 - Miranda Loves Travelling\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mirandalovestravelling.com\/ja\/%e3%83%9e%e3%83%ab%e3%82%bf%ef%bc%8d%e3%82%b4%e3%82%be%e5%b3%b6\/malta_gozo-1-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Miranda Loves Travelling\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Malta_gozo-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/%e3%83%9e%e3%83%ab%e3%82%bf%ef%bc%8d%e3%82%b4%e3%82%be%e5%b3%b6\/malta_gozo-1-2\/\",\"url\":\"https:\/\/mirandalovestravelling.com\/ja\/%e3%83%9e%e3%83%ab%e3%82%bf%ef%bc%8d%e3%82%b4%e3%82%be%e5%b3%b6\/malta_gozo-1-2\/\",\"name\":\"\u30de\u30eb\u30bf\u3001\u30b4\u30be\u5cf6\uff0d\u6e2f\u306e\u5149\u666f 2013\u5e742\u6708 - Miranda Loves Travelling\",\"isPartOf\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/#website\"},\"datePublished\":\"2016-08-12T07:31:35+00:00\",\"dateModified\":\"2016-08-12T07:31:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/%e3%83%9e%e3%83%ab%e3%82%bf%ef%bc%8d%e3%82%b4%e3%82%be%e5%b3%b6\/malta_gozo-1-2\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mirandalovestravelling.com\/ja\/%e3%83%9e%e3%83%ab%e3%82%bf%ef%bc%8d%e3%82%b4%e3%82%be%e5%b3%b6\/malta_gozo-1-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/%e3%83%9e%e3%83%ab%e3%82%bf%ef%bc%8d%e3%82%b4%e3%82%be%e5%b3%b6\/malta_gozo-1-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mirandalovestravelling.com\/ja\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u30de\u30eb\u30bf\",\"item\":\"https:\/\/mirandalovestravelling.com\/ja\/location\/%e3%83%9e%e3%83%ab%e3%82%bf\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u30b4\u30be\u5cf6\",\"item\":\"https:\/\/mirandalovestravelling.com\/ja\/location\/%e3%83%9e%e3%83%ab%e3%82%bf\/%e3%82%b4%e3%82%be%e5%b3%b6\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u30de\u30eb\u30bf\uff0d\u30b4\u30be\u5cf6\",\"item\":\"https:\/\/mirandalovestravelling.com\/ja\/%e3%83%9e%e3%83%ab%e3%82%bf%ef%bc%8d%e3%82%b4%e3%82%be%e5%b3%b6\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"\u30de\u30eb\u30bf\u3001\u30b4\u30be\u5cf6\uff0d\u6e2f\u306e\u5149\u666f 2013\u5e742\u6708\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/#website\",\"url\":\"https:\/\/mirandalovestravelling.com\/ja\/\",\"name\":\"Miranda Loves Travelling\",\"description\":\"\u79c1\u306e\u65c5\u884c\u65e5\u8a18\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mirandalovestravelling.com\/ja\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ja\"}]}<\/script>","yoast_head_json":{"title":"\u30de\u30eb\u30bf\u3001\u30b4\u30be\u5cf6\uff0d\u6e2f\u306e\u5149\u666f 2013\u5e742\u6708 - Miranda Loves Travelling","robots":{"index":"noindex","follow":"follow"},"og_locale":"ja_JP","og_type":"article","og_title":"\u30de\u30eb\u30bf\u3001\u30b4\u30be\u5cf6\uff0d\u6e2f\u306e\u5149\u666f 2013\u5e742\u6708 - Miranda Loves Travelling","og_url":"https:\/\/mirandalovestravelling.com\/ja\/%e3%83%9e%e3%83%ab%e3%82%bf%ef%bc%8d%e3%82%b4%e3%82%be%e5%b3%b6\/malta_gozo-1-2\/","og_site_name":"Miranda Loves Travelling","og_image":[{"width":1000,"height":667,"url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Malta_gozo-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mirandalovestravelling.com\/ja\/%e3%83%9e%e3%83%ab%e3%82%bf%ef%bc%8d%e3%82%b4%e3%82%be%e5%b3%b6\/malta_gozo-1-2\/","url":"https:\/\/mirandalovestravelling.com\/ja\/%e3%83%9e%e3%83%ab%e3%82%bf%ef%bc%8d%e3%82%b4%e3%82%be%e5%b3%b6\/malta_gozo-1-2\/","name":"\u30de\u30eb\u30bf\u3001\u30b4\u30be\u5cf6\uff0d\u6e2f\u306e\u5149\u666f 2013\u5e742\u6708 - Miranda Loves Travelling","isPartOf":{"@id":"https:\/\/mirandalovestravelling.com\/ja\/#website"},"datePublished":"2016-08-12T07:31:35+00:00","dateModified":"2016-08-12T07:31:35+00:00","breadcrumb":{"@id":"https:\/\/mirandalovestravelling.com\/ja\/%e3%83%9e%e3%83%ab%e3%82%bf%ef%bc%8d%e3%82%b4%e3%82%be%e5%b3%b6\/malta_gozo-1-2\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mirandalovestravelling.com\/ja\/%e3%83%9e%e3%83%ab%e3%82%bf%ef%bc%8d%e3%82%b4%e3%82%be%e5%b3%b6\/malta_gozo-1-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mirandalovestravelling.com\/ja\/%e3%83%9e%e3%83%ab%e3%82%bf%ef%bc%8d%e3%82%b4%e3%82%be%e5%b3%b6\/malta_gozo-1-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mirandalovestravelling.com\/ja\/"},{"@type":"ListItem","position":2,"name":"\u30de\u30eb\u30bf","item":"https:\/\/mirandalovestravelling.com\/ja\/location\/%e3%83%9e%e3%83%ab%e3%82%bf\/"},{"@type":"ListItem","position":3,"name":"\u30b4\u30be\u5cf6","item":"https:\/\/mirandalovestravelling.com\/ja\/location\/%e3%83%9e%e3%83%ab%e3%82%bf\/%e3%82%b4%e3%82%be%e5%b3%b6\/"},{"@type":"ListItem","position":4,"name":"\u30de\u30eb\u30bf\uff0d\u30b4\u30be\u5cf6","item":"https:\/\/mirandalovestravelling.com\/ja\/%e3%83%9e%e3%83%ab%e3%82%bf%ef%bc%8d%e3%82%b4%e3%82%be%e5%b3%b6\/"},{"@type":"ListItem","position":5,"name":"\u30de\u30eb\u30bf\u3001\u30b4\u30be\u5cf6\uff0d\u6e2f\u306e\u5149\u666f 2013\u5e742\u6708"}]},{"@type":"WebSite","@id":"https:\/\/mirandalovestravelling.com\/ja\/#website","url":"https:\/\/mirandalovestravelling.com\/ja\/","name":"Miranda Loves Travelling","description":"\u79c1\u306e\u65c5\u884c\u65e5\u8a18","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mirandalovestravelling.com\/ja\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ja"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Malta_gozo-1.jpg'><img width=\"1000\" height=\"667\" src=\"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Malta_gozo-1.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Malta_gozo-1.jpg 1000w, https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Malta_gozo-1-768x512.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1000,"height":667,"file":"2016\/08\/Malta_gozo-1.jpg","sizes":{"thumbnail":{"file":"Malta_gozo-1-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Malta_gozo-1-150x150.jpg"},"medium_large":{"file":"Malta_gozo-1-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Malta_gozo-1-768x512.jpg"},"mlt-medium":{"file":"Malta_gozo-1-326x245.jpg","width":326,"height":245,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Malta_gozo-1-326x245.jpg"},"mlt-small":{"file":"Malta_gozo-1-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Malta_gozo-1-80x60.jpg"},"full":{"file":"Malta_gozo-1.jpg","width":1000,"height":667,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Malta_gozo-1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ShortPixel":{"type":"lossy","exifKept":"0","date":"2019-05-04 21:05:16","thumbsOpt":4,"thumbsOptList":["Malta_gozo-1-150x150.jpg","Malta_gozo-1-768x512.jpg","Malta_gozo-1-326x245.jpg","Malta_gozo-1-80x60.jpg"],"excludeSizes":[],"retinasOpt":0},"ShortPixelImprovement":"46.51"},"post":121442,"source_url":"https:\/\/mirandalovestravelling.com\/media\/2016\/08\/Malta_gozo-1.jpg","_links":{"self":[{"href":"https:\/\/mirandalovestravelling.com\/ja\/wp-json\/wp\/v2\/media\/106761"}],"collection":[{"href":"https:\/\/mirandalovestravelling.com\/ja\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/mirandalovestravelling.com\/ja\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/mirandalovestravelling.com\/ja\/wp-json\/wp\/v2\/users\/11"}]}}