{"id":132119,"date":"2017-03-20T10:52:45","date_gmt":"2017-03-20T10:52:45","guid":{"rendered":"https:\/\/mirandalovestravelling.com\/media\/2017\/03\/Raquira-24.jpg"},"modified":"2017-03-20T11:28:23","modified_gmt":"2017-03-20T11:28:23","slug":"raquira-24-2","status":"inherit","type":"attachment","link":"https:\/\/mirandalovestravelling.com\/ja\/colombia-raquira\/raquira-24-2\/","title":{"rendered":"\u30e9\u30ad\u30e9\uff0d\u30cf\u30f3\u30e2\u30c3\u30af 2016\u5e7412\u6708"},"author":11,"comment_status":"open","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"yoast_head":"<title>\u30e9\u30ad\u30e9\uff0d\u30cf\u30f3\u30e2\u30c3\u30af 2016\u5e7412\u6708 - Miranda Loves Travelling<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u30e9\u30ad\u30e9\uff0d\u30cf\u30f3\u30e2\u30c3\u30af 2016\u5e7412\u6708 - Miranda Loves Travelling\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mirandalovestravelling.com\/ja\/colombia-raquira\/raquira-24-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Miranda Loves Travelling\" \/>\n<meta property=\"article:modified_time\" content=\"2017-03-20T11:28:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mirandalovestravelling.com\/media\/2017\/03\/Raquira-24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/colombia-raquira\/raquira-24-2\/\",\"url\":\"https:\/\/mirandalovestravelling.com\/ja\/colombia-raquira\/raquira-24-2\/\",\"name\":\"\u30e9\u30ad\u30e9\uff0d\u30cf\u30f3\u30e2\u30c3\u30af 2016\u5e7412\u6708 - Miranda Loves Travelling\",\"isPartOf\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/#website\"},\"datePublished\":\"2017-03-20T10:52:45+00:00\",\"dateModified\":\"2017-03-20T11:28:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/colombia-raquira\/raquira-24-2\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mirandalovestravelling.com\/ja\/colombia-raquira\/raquira-24-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/colombia-raquira\/raquira-24-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mirandalovestravelling.com\/ja\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u30b3\u30ed\u30f3\u30d3\u30a2\",\"item\":\"https:\/\/mirandalovestravelling.com\/ja\/location\/%e3%82%b3%e3%83%ad%e3%83%b3%e3%83%93%e3%82%a2\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u30e9\u30ad\u30e9\",\"item\":\"https:\/\/mirandalovestravelling.com\/ja\/location\/%e3%82%b3%e3%83%ad%e3%83%b3%e3%83%93%e3%82%a2\/%e3%83%a9%e3%82%ad%e3%83%a9\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u30b3\u30ed\u30f3\u30d3\u30a2\u3001\u30e9\u30ad\u30e9\",\"item\":\"https:\/\/mirandalovestravelling.com\/ja\/colombia-raquira\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"\u30e9\u30ad\u30e9\uff0d\u30cf\u30f3\u30e2\u30c3\u30af 2016\u5e7412\u6708\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/#website\",\"url\":\"https:\/\/mirandalovestravelling.com\/ja\/\",\"name\":\"Miranda Loves Travelling\",\"description\":\"\u79c1\u306e\u65c5\u884c\u65e5\u8a18\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mirandalovestravelling.com\/ja\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ja\"}]}<\/script>","yoast_head_json":{"title":"\u30e9\u30ad\u30e9\uff0d\u30cf\u30f3\u30e2\u30c3\u30af 2016\u5e7412\u6708 - Miranda Loves Travelling","robots":{"index":"noindex","follow":"follow"},"og_locale":"ja_JP","og_type":"article","og_title":"\u30e9\u30ad\u30e9\uff0d\u30cf\u30f3\u30e2\u30c3\u30af 2016\u5e7412\u6708 - Miranda Loves Travelling","og_url":"https:\/\/mirandalovestravelling.com\/ja\/colombia-raquira\/raquira-24-2\/","og_site_name":"Miranda Loves Travelling","article_modified_time":"2017-03-20T11:28:23+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/mirandalovestravelling.com\/media\/2017\/03\/Raquira-24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mirandalovestravelling.com\/ja\/colombia-raquira\/raquira-24-2\/","url":"https:\/\/mirandalovestravelling.com\/ja\/colombia-raquira\/raquira-24-2\/","name":"\u30e9\u30ad\u30e9\uff0d\u30cf\u30f3\u30e2\u30c3\u30af 2016\u5e7412\u6708 - Miranda Loves Travelling","isPartOf":{"@id":"https:\/\/mirandalovestravelling.com\/ja\/#website"},"datePublished":"2017-03-20T10:52:45+00:00","dateModified":"2017-03-20T11:28:23+00:00","breadcrumb":{"@id":"https:\/\/mirandalovestravelling.com\/ja\/colombia-raquira\/raquira-24-2\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mirandalovestravelling.com\/ja\/colombia-raquira\/raquira-24-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mirandalovestravelling.com\/ja\/colombia-raquira\/raquira-24-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mirandalovestravelling.com\/ja\/"},{"@type":"ListItem","position":2,"name":"\u30b3\u30ed\u30f3\u30d3\u30a2","item":"https:\/\/mirandalovestravelling.com\/ja\/location\/%e3%82%b3%e3%83%ad%e3%83%b3%e3%83%93%e3%82%a2\/"},{"@type":"ListItem","position":3,"name":"\u30e9\u30ad\u30e9","item":"https:\/\/mirandalovestravelling.com\/ja\/location\/%e3%82%b3%e3%83%ad%e3%83%b3%e3%83%93%e3%82%a2\/%e3%83%a9%e3%82%ad%e3%83%a9\/"},{"@type":"ListItem","position":4,"name":"\u30b3\u30ed\u30f3\u30d3\u30a2\u3001\u30e9\u30ad\u30e9","item":"https:\/\/mirandalovestravelling.com\/ja\/colombia-raquira\/"},{"@type":"ListItem","position":5,"name":"\u30e9\u30ad\u30e9\uff0d\u30cf\u30f3\u30e2\u30c3\u30af 2016\u5e7412\u6708"}]},{"@type":"WebSite","@id":"https:\/\/mirandalovestravelling.com\/ja\/#website","url":"https:\/\/mirandalovestravelling.com\/ja\/","name":"Miranda Loves Travelling","description":"\u79c1\u306e\u65c5\u884c\u65e5\u8a18","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mirandalovestravelling.com\/ja\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ja"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/mirandalovestravelling.com\/media\/2017\/03\/Raquira-24.jpg'><img width=\"1920\" height=\"1280\" src=\"https:\/\/mirandalovestravelling.com\/media\/2017\/03\/Raquira-24.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/mirandalovestravelling.com\/media\/2017\/03\/Raquira-24.jpg 1920w, https:\/\/mirandalovestravelling.com\/media\/2017\/03\/Raquira-24-768x512.jpg 768w, https:\/\/mirandalovestravelling.com\/media\/2017\/03\/Raquira-24-336x224.jpg 336w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":1280,"file":"2017\/03\/Raquira-24.jpg","sizes":{"thumbnail":{"file":"Raquira-24-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2017\/03\/Raquira-24-150x150.jpg"},"medium_large":{"file":"Raquira-24-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2017\/03\/Raquira-24-768x512.jpg"},"mlt-medium":{"file":"Raquira-24-336x224.jpg","width":336,"height":224,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2017\/03\/Raquira-24-336x224.jpg"},"mlt-small":{"file":"Raquira-24-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2017\/03\/Raquira-24-80x60.jpg"},"full":{"file":"Raquira-24.jpg","width":1920,"height":1280,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2017\/03\/Raquira-24.jpg"}},"image_meta":{"aperture":"8","credit":"www.mirandalovestravelling.jp","camera":"Canon EOS 1100D","caption":"","created_timestamp":"1482683724","copyright":"","focal_length":"63","iso":"200","shutter_speed":"0.005","title":"","orientation":"1","keywords":[]},"ShortPixel":{"type":"lossy","exifKept":"0","date":"2019-05-06 02:10:01","thumbsOpt":4,"thumbsOptList":["Raquira-24-150x150.jpg","Raquira-24-768x512.jpg","Raquira-24-336x224.jpg","Raquira-24-80x60.jpg"],"excludeSizes":[],"retinasOpt":0},"ShortPixelImprovement":"73.48"},"post":132141,"source_url":"https:\/\/mirandalovestravelling.com\/media\/2017\/03\/Raquira-24.jpg","_links":{"self":[{"href":"https:\/\/mirandalovestravelling.com\/ja\/wp-json\/wp\/v2\/media\/132119"}],"collection":[{"href":"https:\/\/mirandalovestravelling.com\/ja\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/mirandalovestravelling.com\/ja\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/mirandalovestravelling.com\/ja\/wp-json\/wp\/v2\/users\/11"}]}}