{"id":180788,"date":"2018-06-08T09:45:02","date_gmt":"2018-06-08T09:45:02","guid":{"rendered":"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Sulmona-3.jpg"},"modified":"2020-12-19T16:16:28","modified_gmt":"2020-12-19T16:16:28","slug":"sulmona-3-2","status":"inherit","type":"attachment","link":"https:\/\/mirandalovestravelling.com\/ja\/%e3%82%a4%e3%82%bf%e3%83%aa%e3%82%a2%e3%80%81%e3%82%a2%e3%83%96%e3%83%ab%e3%83%83%e3%83%84%e3%82%a9\/sulmona-3-2\/","title":{"rendered":"Sulmona (3)"},"author":11,"comment_status":"open","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"yoast_head":"<title>Sulmona (3) - Miranda Loves Travelling<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sulmona (3) - Miranda Loves Travelling\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mirandalovestravelling.com\/ja\/%e3%82%a4%e3%82%bf%e3%83%aa%e3%82%a2%e3%80%81%e3%82%a2%e3%83%96%e3%83%ab%e3%83%83%e3%83%84%e3%82%a9\/sulmona-3-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Miranda Loves Travelling\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-19T16:16:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Sulmona-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/%e3%82%a4%e3%82%bf%e3%83%aa%e3%82%a2%e3%80%81%e3%82%a2%e3%83%96%e3%83%ab%e3%83%83%e3%83%84%e3%82%a9\/sulmona-3-2\/\",\"url\":\"https:\/\/mirandalovestravelling.com\/ja\/%e3%82%a4%e3%82%bf%e3%83%aa%e3%82%a2%e3%80%81%e3%82%a2%e3%83%96%e3%83%ab%e3%83%83%e3%83%84%e3%82%a9\/sulmona-3-2\/\",\"name\":\"Sulmona (3) - Miranda Loves Travelling\",\"isPartOf\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/#website\"},\"datePublished\":\"2018-06-08T09:45:02+00:00\",\"dateModified\":\"2020-12-19T16:16:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/%e3%82%a4%e3%82%bf%e3%83%aa%e3%82%a2%e3%80%81%e3%82%a2%e3%83%96%e3%83%ab%e3%83%83%e3%83%84%e3%82%a9\/sulmona-3-2\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mirandalovestravelling.com\/ja\/%e3%82%a4%e3%82%bf%e3%83%aa%e3%82%a2%e3%80%81%e3%82%a2%e3%83%96%e3%83%ab%e3%83%83%e3%83%84%e3%82%a9\/sulmona-3-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/%e3%82%a4%e3%82%bf%e3%83%aa%e3%82%a2%e3%80%81%e3%82%a2%e3%83%96%e3%83%ab%e3%83%83%e3%83%84%e3%82%a9\/sulmona-3-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mirandalovestravelling.com\/ja\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u30a4\u30bf\u30ea\u30a2\",\"item\":\"https:\/\/mirandalovestravelling.com\/ja\/location\/%e3%82%a4%e3%82%bf%e3%83%aa%e3%82%a2\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u30a2\u30d6\u30eb\u30c3\u30c4\u30a9\",\"item\":\"https:\/\/mirandalovestravelling.com\/ja\/location\/%e3%82%a4%e3%82%bf%e3%83%aa%e3%82%a2\/%e3%82%a2%e3%83%96%e3%83%ab%e3%83%83%e3%83%84%e3%82%a9\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u30a4\u30bf\u30ea\u30a2\u3001\u30a2\u30d6\u30eb\u30c3\u30c4\u30a9\",\"item\":\"https:\/\/mirandalovestravelling.com\/ja\/%e3%82%a4%e3%82%bf%e3%83%aa%e3%82%a2%e3%80%81%e3%82%a2%e3%83%96%e3%83%ab%e3%83%83%e3%83%84%e3%82%a9\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Sulmona (3)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/#website\",\"url\":\"https:\/\/mirandalovestravelling.com\/ja\/\",\"name\":\"Miranda Loves Travelling\",\"description\":\"\u79c1\u306e\u65c5\u884c\u65e5\u8a18\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mirandalovestravelling.com\/ja\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ja\"}]}<\/script>","yoast_head_json":{"title":"Sulmona (3) - Miranda Loves Travelling","robots":{"index":"noindex","follow":"follow"},"og_locale":"ja_JP","og_type":"article","og_title":"Sulmona (3) - Miranda Loves Travelling","og_url":"https:\/\/mirandalovestravelling.com\/ja\/%e3%82%a4%e3%82%bf%e3%83%aa%e3%82%a2%e3%80%81%e3%82%a2%e3%83%96%e3%83%ab%e3%83%83%e3%83%84%e3%82%a9\/sulmona-3-2\/","og_site_name":"Miranda Loves Travelling","article_modified_time":"2020-12-19T16:16:28+00:00","og_image":[{"width":1920,"height":1272,"url":"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Sulmona-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mirandalovestravelling.com\/ja\/%e3%82%a4%e3%82%bf%e3%83%aa%e3%82%a2%e3%80%81%e3%82%a2%e3%83%96%e3%83%ab%e3%83%83%e3%83%84%e3%82%a9\/sulmona-3-2\/","url":"https:\/\/mirandalovestravelling.com\/ja\/%e3%82%a4%e3%82%bf%e3%83%aa%e3%82%a2%e3%80%81%e3%82%a2%e3%83%96%e3%83%ab%e3%83%83%e3%83%84%e3%82%a9\/sulmona-3-2\/","name":"Sulmona (3) - Miranda Loves Travelling","isPartOf":{"@id":"https:\/\/mirandalovestravelling.com\/ja\/#website"},"datePublished":"2018-06-08T09:45:02+00:00","dateModified":"2020-12-19T16:16:28+00:00","breadcrumb":{"@id":"https:\/\/mirandalovestravelling.com\/ja\/%e3%82%a4%e3%82%bf%e3%83%aa%e3%82%a2%e3%80%81%e3%82%a2%e3%83%96%e3%83%ab%e3%83%83%e3%83%84%e3%82%a9\/sulmona-3-2\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mirandalovestravelling.com\/ja\/%e3%82%a4%e3%82%bf%e3%83%aa%e3%82%a2%e3%80%81%e3%82%a2%e3%83%96%e3%83%ab%e3%83%83%e3%83%84%e3%82%a9\/sulmona-3-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mirandalovestravelling.com\/ja\/%e3%82%a4%e3%82%bf%e3%83%aa%e3%82%a2%e3%80%81%e3%82%a2%e3%83%96%e3%83%ab%e3%83%83%e3%83%84%e3%82%a9\/sulmona-3-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mirandalovestravelling.com\/ja\/"},{"@type":"ListItem","position":2,"name":"\u30a4\u30bf\u30ea\u30a2","item":"https:\/\/mirandalovestravelling.com\/ja\/location\/%e3%82%a4%e3%82%bf%e3%83%aa%e3%82%a2\/"},{"@type":"ListItem","position":3,"name":"\u30a2\u30d6\u30eb\u30c3\u30c4\u30a9","item":"https:\/\/mirandalovestravelling.com\/ja\/location\/%e3%82%a4%e3%82%bf%e3%83%aa%e3%82%a2\/%e3%82%a2%e3%83%96%e3%83%ab%e3%83%83%e3%83%84%e3%82%a9\/"},{"@type":"ListItem","position":4,"name":"\u30a4\u30bf\u30ea\u30a2\u3001\u30a2\u30d6\u30eb\u30c3\u30c4\u30a9","item":"https:\/\/mirandalovestravelling.com\/ja\/%e3%82%a4%e3%82%bf%e3%83%aa%e3%82%a2%e3%80%81%e3%82%a2%e3%83%96%e3%83%ab%e3%83%83%e3%83%84%e3%82%a9\/"},{"@type":"ListItem","position":5,"name":"Sulmona (3)"}]},{"@type":"WebSite","@id":"https:\/\/mirandalovestravelling.com\/ja\/#website","url":"https:\/\/mirandalovestravelling.com\/ja\/","name":"Miranda Loves Travelling","description":"\u79c1\u306e\u65c5\u884c\u65e5\u8a18","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mirandalovestravelling.com\/ja\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ja"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Sulmona-3.jpg'><img width=\"1920\" height=\"1272\" src=\"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Sulmona-3.jpg\" class=\"attachment-medium size-medium\" alt=\"Confetti di Sulmona\" decoding=\"async\" srcset=\"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Sulmona-3.jpg 1920w, https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Sulmona-3-768x509.jpg 768w, https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Sulmona-3-336x223.jpg 336w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Confetti di Sulmona","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":1272,"file":"2018\/01\/Sulmona-3.jpg","sizes":{"thumbnail":{"file":"Sulmona-3-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Sulmona-3-150x150.jpg"},"medium_large":{"file":"Sulmona-3-768x509.jpg","width":768,"height":509,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Sulmona-3-768x509.jpg"},"mlt-medium":{"file":"Sulmona-3-336x223.jpg","width":336,"height":223,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Sulmona-3-336x223.jpg"},"mlt-small":{"file":"Sulmona-3-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Sulmona-3-80x60.jpg"},"full":{"file":"Sulmona-3.jpg","width":1920,"height":1272,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Sulmona-3.jpg"}},"image_meta":{"aperture":"6","credit":"","camera":"NIKON D5100","caption":"","created_timestamp":"1524285080","copyright":"","focal_length":"125","iso":"100","shutter_speed":"0.0025","title":"","orientation":"1","keywords":[]},"ShortPixel":{"type":"lossy","exifKept":"0","date":"2019-04-24 15:32:54","thumbsOpt":4,"thumbsOptList":["Sulmona-3-150x150.jpg","Sulmona-3-768x509.jpg","Sulmona-3-336x223.jpg","Sulmona-3-80x60.jpg"],"excludeSizes":[],"retinasOpt":0},"ShortPixelImprovement":"40.45"},"post":173508,"source_url":"https:\/\/mirandalovestravelling.com\/media\/2018\/01\/Sulmona-3.jpg","_links":{"self":[{"href":"https:\/\/mirandalovestravelling.com\/ja\/wp-json\/wp\/v2\/media\/180788"}],"collection":[{"href":"https:\/\/mirandalovestravelling.com\/ja\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/mirandalovestravelling.com\/ja\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/mirandalovestravelling.com\/ja\/wp-json\/wp\/v2\/users\/11"}]}}