{"id":211920,"date":"2020-04-08T18:44:28","date_gmt":"2020-04-08T18:44:28","guid":{"rendered":"https:\/\/mirandalovestravelling.com\/media\/2020\/04\/Hong-Kong-7.jpg"},"modified":"2020-04-08T18:44:28","modified_gmt":"2020-04-08T18:44:28","slug":"hong-kong-7-2","status":"inherit","type":"attachment","link":"https:\/\/mirandalovestravelling.com\/ja\/%e9%a6%99%e6%b8%af\/hong-kong-7-2\/","title":{"rendered":"Hong Kong (7)"},"author":10,"comment_status":"open","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"yoast_head":"<title>Hong Kong (7) - Miranda Loves Travelling<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hong Kong (7) - Miranda Loves Travelling\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mirandalovestravelling.com\/ja\/%e9%a6%99%e6%b8%af\/hong-kong-7-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Miranda Loves Travelling\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mirandalovestravelling.com\/media\/2020\/04\/Hong-Kong-7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1788\" \/>\n\t<meta property=\"og:image:height\" content=\"1194\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/%e9%a6%99%e6%b8%af\/hong-kong-7-2\/\",\"url\":\"https:\/\/mirandalovestravelling.com\/ja\/%e9%a6%99%e6%b8%af\/hong-kong-7-2\/\",\"name\":\"Hong Kong (7) - Miranda Loves Travelling\",\"isPartOf\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/#website\"},\"datePublished\":\"2020-04-08T18:44:28+00:00\",\"dateModified\":\"2020-04-08T18:44:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/%e9%a6%99%e6%b8%af\/hong-kong-7-2\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mirandalovestravelling.com\/ja\/%e9%a6%99%e6%b8%af\/hong-kong-7-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/%e9%a6%99%e6%b8%af\/hong-kong-7-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mirandalovestravelling.com\/ja\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u9999\u6e2f\",\"item\":\"https:\/\/mirandalovestravelling.com\/ja\/location\/%e9%a6%99%e6%b8%af\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u9999\u6e2f\",\"item\":\"https:\/\/mirandalovestravelling.com\/ja\/%e9%a6%99%e6%b8%af\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Hong Kong (7)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/#website\",\"url\":\"https:\/\/mirandalovestravelling.com\/ja\/\",\"name\":\"Miranda Loves Travelling\",\"description\":\"\u79c1\u306e\u65c5\u884c\u65e5\u8a18\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mirandalovestravelling.com\/ja\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ja\"}]}<\/script>","yoast_head_json":{"title":"Hong Kong (7) - Miranda Loves Travelling","robots":{"index":"noindex","follow":"follow"},"og_locale":"ja_JP","og_type":"article","og_title":"Hong Kong (7) - Miranda Loves Travelling","og_url":"https:\/\/mirandalovestravelling.com\/ja\/%e9%a6%99%e6%b8%af\/hong-kong-7-2\/","og_site_name":"Miranda Loves Travelling","og_image":[{"width":1788,"height":1194,"url":"https:\/\/mirandalovestravelling.com\/media\/2020\/04\/Hong-Kong-7.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mirandalovestravelling.com\/ja\/%e9%a6%99%e6%b8%af\/hong-kong-7-2\/","url":"https:\/\/mirandalovestravelling.com\/ja\/%e9%a6%99%e6%b8%af\/hong-kong-7-2\/","name":"Hong Kong (7) - Miranda Loves Travelling","isPartOf":{"@id":"https:\/\/mirandalovestravelling.com\/ja\/#website"},"datePublished":"2020-04-08T18:44:28+00:00","dateModified":"2020-04-08T18:44:28+00:00","breadcrumb":{"@id":"https:\/\/mirandalovestravelling.com\/ja\/%e9%a6%99%e6%b8%af\/hong-kong-7-2\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mirandalovestravelling.com\/ja\/%e9%a6%99%e6%b8%af\/hong-kong-7-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mirandalovestravelling.com\/ja\/%e9%a6%99%e6%b8%af\/hong-kong-7-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mirandalovestravelling.com\/ja\/"},{"@type":"ListItem","position":2,"name":"\u9999\u6e2f","item":"https:\/\/mirandalovestravelling.com\/ja\/location\/%e9%a6%99%e6%b8%af\/"},{"@type":"ListItem","position":3,"name":"\u9999\u6e2f","item":"https:\/\/mirandalovestravelling.com\/ja\/%e9%a6%99%e6%b8%af\/"},{"@type":"ListItem","position":4,"name":"Hong Kong (7)"}]},{"@type":"WebSite","@id":"https:\/\/mirandalovestravelling.com\/ja\/#website","url":"https:\/\/mirandalovestravelling.com\/ja\/","name":"Miranda Loves Travelling","description":"\u79c1\u306e\u65c5\u884c\u65e5\u8a18","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mirandalovestravelling.com\/ja\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ja"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/mirandalovestravelling.com\/media\/2020\/04\/Hong-Kong-7.jpg'><img width=\"1788\" height=\"1194\" src=\"https:\/\/mirandalovestravelling.com\/media\/2020\/04\/Hong-Kong-7.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/mirandalovestravelling.com\/media\/2020\/04\/Hong-Kong-7.jpg 1788w, https:\/\/mirandalovestravelling.com\/media\/2020\/04\/Hong-Kong-7-768x513.jpg 768w, https:\/\/mirandalovestravelling.com\/media\/2020\/04\/Hong-Kong-7-336x224.jpg 336w\" sizes=\"(max-width: 1788px) 100vw, 1788px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1788,"height":1194,"file":"2020\/04\/Hong-Kong-7.jpg","sizes":{"thumbnail":{"file":"Hong-Kong-7-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2020\/04\/Hong-Kong-7-150x150.jpg"},"medium_large":{"file":"Hong-Kong-7-768x513.jpg","width":768,"height":513,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2020\/04\/Hong-Kong-7-768x513.jpg"},"mlt-medium":{"file":"Hong-Kong-7-336x224.jpg","width":336,"height":224,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2020\/04\/Hong-Kong-7-336x224.jpg"},"mlt-small":{"file":"Hong-Kong-7-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2020\/04\/Hong-Kong-7-80x60.jpg"},"full":{"file":"Hong-Kong-7.jpg","width":1788,"height":1194,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2020\/04\/Hong-Kong-7.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ShortPixel":{"type":"lossy","exifKept":"0","date":"2020-04-08 20:45:47","thumbsOpt":4,"thumbsOptList":["Hong-Kong-7-150x150.jpg","Hong-Kong-7-768x513.jpg","Hong-Kong-7-336x224.jpg","Hong-Kong-7-80x60.jpg"],"excludeSizes":[],"retinasOpt":0},"ShortPixelImprovement":"65.97"},"post":211924,"source_url":"https:\/\/mirandalovestravelling.com\/media\/2020\/04\/Hong-Kong-7.jpg","_links":{"self":[{"href":"https:\/\/mirandalovestravelling.com\/ja\/wp-json\/wp\/v2\/media\/211920"}],"collection":[{"href":"https:\/\/mirandalovestravelling.com\/ja\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/mirandalovestravelling.com\/ja\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/mirandalovestravelling.com\/ja\/wp-json\/wp\/v2\/users\/10"}]}}