{"id":243073,"date":"2023-03-21T09:12:22","date_gmt":"2023-03-21T09:12:22","guid":{"rendered":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-31.jpg"},"modified":"2023-03-21T09:12:22","modified_gmt":"2023-03-21T09:12:22","slug":"barcelona-2022-31-2","status":"inherit","type":"attachment","link":"https:\/\/mirandalovestravelling.com\/ja\/barcelona-2022-31-2\/","title":{"rendered":"Barcelona 2022 (31)"},"author":10,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"yoast_head":"<title>Barcelona 2022 (31) - Miranda Loves Travelling<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Barcelona 2022 (31) - Miranda Loves Travelling\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mirandalovestravelling.com\/ja\/barcelona-2022-31-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Miranda Loves Travelling\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-31-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/barcelona-2022-31-2\/\",\"url\":\"https:\/\/mirandalovestravelling.com\/ja\/barcelona-2022-31-2\/\",\"name\":\"Barcelona 2022 (31) - Miranda Loves Travelling\",\"isPartOf\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/#website\"},\"datePublished\":\"2023-03-21T09:12:22+00:00\",\"dateModified\":\"2023-03-21T09:12:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/barcelona-2022-31-2\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mirandalovestravelling.com\/ja\/barcelona-2022-31-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/barcelona-2022-31-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mirandalovestravelling.com\/ja\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Barcelona 2022 (31)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/#website\",\"url\":\"https:\/\/mirandalovestravelling.com\/ja\/\",\"name\":\"Miranda Loves Travelling\",\"description\":\"\u79c1\u306e\u65c5\u884c\u65e5\u8a18\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mirandalovestravelling.com\/ja\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ja\"}]}<\/script>","yoast_head_json":{"title":"Barcelona 2022 (31) - Miranda Loves Travelling","robots":{"index":"noindex","follow":"follow"},"og_locale":"ja_JP","og_type":"article","og_title":"Barcelona 2022 (31) - Miranda Loves Travelling","og_url":"https:\/\/mirandalovestravelling.com\/ja\/barcelona-2022-31-2\/","og_site_name":"Miranda Loves Travelling","og_image":[{"width":1920,"height":1280,"url":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-31-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mirandalovestravelling.com\/ja\/barcelona-2022-31-2\/","url":"https:\/\/mirandalovestravelling.com\/ja\/barcelona-2022-31-2\/","name":"Barcelona 2022 (31) - Miranda Loves Travelling","isPartOf":{"@id":"https:\/\/mirandalovestravelling.com\/ja\/#website"},"datePublished":"2023-03-21T09:12:22+00:00","dateModified":"2023-03-21T09:12:22+00:00","breadcrumb":{"@id":"https:\/\/mirandalovestravelling.com\/ja\/barcelona-2022-31-2\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mirandalovestravelling.com\/ja\/barcelona-2022-31-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mirandalovestravelling.com\/ja\/barcelona-2022-31-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mirandalovestravelling.com\/ja\/"},{"@type":"ListItem","position":2,"name":"Barcelona 2022 (31)"}]},{"@type":"WebSite","@id":"https:\/\/mirandalovestravelling.com\/ja\/#website","url":"https:\/\/mirandalovestravelling.com\/ja\/","name":"Miranda Loves Travelling","description":"\u79c1\u306e\u65c5\u884c\u65e5\u8a18","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mirandalovestravelling.com\/ja\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ja"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-31-scaled.jpg'><img width=\"1920\" height=\"1280\" src=\"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-31-scaled.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-31-scaled.jpg 1920w, https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-31-768x512.jpg 768w, https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-31-1536x1024.jpg 1536w, https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-31-336x224.jpg 336w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":1280,"file":"2023\/03\/Barcelona-2022-31-scaled.jpg","filesize":223738,"sizes":{"thumbnail":{"file":"Barcelona-2022-31-150x150.jpg","width":150,"height":150,"filesize":6396,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-31-150x150.jpg"},"medium_large":{"file":"Barcelona-2022-31-768x512.jpg","width":768,"height":512,"filesize":73578,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-31-768x512.jpg"},"1536x1536":{"file":"Barcelona-2022-31-1536x1024.jpg","width":1536,"height":1024,"filesize":148209,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-31-1536x1024.jpg"},"2048x2048":{"file":"Barcelona-2022-31-2048x1365.jpg","width":1920,"height":1280,"filesize":219049,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-31-2048x1365.jpg"},"mlt-medium":{"file":"Barcelona-2022-31-336x224.jpg","width":336,"height":224,"filesize":20018,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-31-336x224.jpg"},"mlt-small":{"file":"Barcelona-2022-31-80x60.jpg","width":80,"height":60,"filesize":1842,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-31-80x60.jpg"},"full":{"file":"Barcelona-2022-31-scaled.jpg","width":1920,"height":1280,"mime_type":"image\/jpeg","source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-31-scaled.jpg"}},"image_meta":{"aperture":"4","credit":"","camera":"NIKON 1 V2","caption":"","created_timestamp":"1668336328","copyright":"","focal_length":"10","iso":"640","shutter_speed":"0.016666666666667","title":"","orientation":"1","keywords":[]},"original_image":"Barcelona-2022-31.jpg"},"post":null,"source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/03\/Barcelona-2022-31-scaled.jpg","_links":{"self":[{"href":"https:\/\/mirandalovestravelling.com\/ja\/wp-json\/wp\/v2\/media\/243073"}],"collection":[{"href":"https:\/\/mirandalovestravelling.com\/ja\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/mirandalovestravelling.com\/ja\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/mirandalovestravelling.com\/ja\/wp-json\/wp\/v2\/users\/10"}]}}