{"id":244224,"date":"2023-06-06T16:12:47","date_gmt":"2023-06-06T16:12:47","guid":{"rendered":"https:\/\/mirandalovestravelling.com\/media\/2023\/06\/Salamanca-2022-41.jpg"},"modified":"2023-06-06T16:22:22","modified_gmt":"2023-06-06T16:22:22","slug":"salamanca-2022-41-2","status":"inherit","type":"attachment","link":"https:\/\/mirandalovestravelling.com\/ja\/%e7%be%8e%e3%81%97%e3%81%84casa-lis\/salamanca-2022-41-2\/","title":{"rendered":"Salamanca 2022 (41)"},"author":10,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"Relevanssi image attachment filter Relevanssi index exclude"},"yoast_head":"<title>Salamanca 2022 (41) - Miranda Loves Travelling<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salamanca 2022 (41) - Miranda Loves Travelling\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mirandalovestravelling.com\/ja\/%e7%be%8e%e3%81%97%e3%81%84casa-lis\/salamanca-2022-41-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Miranda Loves Travelling\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-06T16:22:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mirandalovestravelling.com\/media\/2023\/06\/Salamanca-2022-41.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/%e7%be%8e%e3%81%97%e3%81%84casa-lis\/salamanca-2022-41-2\/\",\"url\":\"https:\/\/mirandalovestravelling.com\/ja\/%e7%be%8e%e3%81%97%e3%81%84casa-lis\/salamanca-2022-41-2\/\",\"name\":\"Salamanca 2022 (41) - Miranda Loves Travelling\",\"isPartOf\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/#website\"},\"datePublished\":\"2023-06-06T16:12:47+00:00\",\"dateModified\":\"2023-06-06T16:22:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/%e7%be%8e%e3%81%97%e3%81%84casa-lis\/salamanca-2022-41-2\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mirandalovestravelling.com\/ja\/%e7%be%8e%e3%81%97%e3%81%84casa-lis\/salamanca-2022-41-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/%e7%be%8e%e3%81%97%e3%81%84casa-lis\/salamanca-2022-41-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mirandalovestravelling.com\/ja\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u30b9\u30da\u30a4\u30f3\",\"item\":\"https:\/\/mirandalovestravelling.com\/ja\/location\/%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u30b5\u30e9\u30de\u30f3\u30ab\",\"item\":\"https:\/\/mirandalovestravelling.com\/ja\/location\/%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3\/%e3%82%b5%e3%83%a9%e3%83%9e%e3%83%b3%e3%82%ab\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u7f8e\u3057\u3044Casa Lis\",\"item\":\"https:\/\/mirandalovestravelling.com\/ja\/?p=244209\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Salamanca 2022 (41)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mirandalovestravelling.com\/ja\/#website\",\"url\":\"https:\/\/mirandalovestravelling.com\/ja\/\",\"name\":\"Miranda Loves Travelling\",\"description\":\"\u79c1\u306e\u65c5\u884c\u65e5\u8a18\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mirandalovestravelling.com\/ja\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ja\"}]}<\/script>","yoast_head_json":{"title":"Salamanca 2022 (41) - Miranda Loves Travelling","robots":{"index":"noindex","follow":"follow"},"og_locale":"ja_JP","og_type":"article","og_title":"Salamanca 2022 (41) - Miranda Loves Travelling","og_url":"https:\/\/mirandalovestravelling.com\/ja\/%e7%be%8e%e3%81%97%e3%81%84casa-lis\/salamanca-2022-41-2\/","og_site_name":"Miranda Loves Travelling","article_modified_time":"2023-06-06T16:22:22+00:00","og_image":[{"width":1920,"height":1440,"url":"https:\/\/mirandalovestravelling.com\/media\/2023\/06\/Salamanca-2022-41.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mirandalovestravelling.com\/ja\/%e7%be%8e%e3%81%97%e3%81%84casa-lis\/salamanca-2022-41-2\/","url":"https:\/\/mirandalovestravelling.com\/ja\/%e7%be%8e%e3%81%97%e3%81%84casa-lis\/salamanca-2022-41-2\/","name":"Salamanca 2022 (41) - Miranda Loves Travelling","isPartOf":{"@id":"https:\/\/mirandalovestravelling.com\/ja\/#website"},"datePublished":"2023-06-06T16:12:47+00:00","dateModified":"2023-06-06T16:22:22+00:00","breadcrumb":{"@id":"https:\/\/mirandalovestravelling.com\/ja\/%e7%be%8e%e3%81%97%e3%81%84casa-lis\/salamanca-2022-41-2\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mirandalovestravelling.com\/ja\/%e7%be%8e%e3%81%97%e3%81%84casa-lis\/salamanca-2022-41-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mirandalovestravelling.com\/ja\/%e7%be%8e%e3%81%97%e3%81%84casa-lis\/salamanca-2022-41-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mirandalovestravelling.com\/ja\/"},{"@type":"ListItem","position":2,"name":"\u30b9\u30da\u30a4\u30f3","item":"https:\/\/mirandalovestravelling.com\/ja\/location\/%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3\/"},{"@type":"ListItem","position":3,"name":"\u30b5\u30e9\u30de\u30f3\u30ab","item":"https:\/\/mirandalovestravelling.com\/ja\/location\/%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3\/%e3%82%b5%e3%83%a9%e3%83%9e%e3%83%b3%e3%82%ab\/"},{"@type":"ListItem","position":4,"name":"\u7f8e\u3057\u3044Casa Lis","item":"https:\/\/mirandalovestravelling.com\/ja\/?p=244209"},{"@type":"ListItem","position":5,"name":"Salamanca 2022 (41)"}]},{"@type":"WebSite","@id":"https:\/\/mirandalovestravelling.com\/ja\/#website","url":"https:\/\/mirandalovestravelling.com\/ja\/","name":"Miranda Loves Travelling","description":"\u79c1\u306e\u65c5\u884c\u65e5\u8a18","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mirandalovestravelling.com\/ja\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ja"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/mirandalovestravelling.com\/media\/2023\/06\/Salamanca-2022-41.jpg'><img width=\"1920\" height=\"1440\" src=\"https:\/\/mirandalovestravelling.com\/media\/2023\/06\/Salamanca-2022-41.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":1440,"filesize":132291,"sizes":{}},"post":244209,"source_url":"https:\/\/mirandalovestravelling.com\/media\/2023\/06\/Salamanca-2022-41.jpg","_links":{"self":[{"href":"https:\/\/mirandalovestravelling.com\/ja\/wp-json\/wp\/v2\/media\/244224"}],"collection":[{"href":"https:\/\/mirandalovestravelling.com\/ja\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/mirandalovestravelling.com\/ja\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/mirandalovestravelling.com\/ja\/wp-json\/wp\/v2\/users\/10"}]}}